{"id":416,"date":"2018-10-29T19:54:14","date_gmt":"2018-10-29T19:54:14","guid":{"rendered":"https:\/\/lifeword.org\/spanish\/?p=416"},"modified":"2019-04-17T19:56:30","modified_gmt":"2019-04-17T19:56:30","slug":"misioneros-dedicados-1","status":"publish","type":"post","link":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/","title":{"rendered":"Misioneros Dedicados &#8211; #1"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cYo pues, preso en el Se\u00f1or, os ruego que and\u00e9is como es digno de la vocaci\u00f3n con que fuisteis llamados,\u201d \u202d\u202dEfesios\u202c \u202d4:1\u202c \u202dRVR1960\u202c\u202c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la vida cristiana no todo es color de rosa, nuestra vida en este mundo no es semejante a un crucero de placer, sino m\u00e1s bien a un campo de batalla. El Ap\u00f3stol Pablo entend\u00eda bien esto, \u00e9l entend\u00eda que vivir una vida en obediencia, fidelidad y lealtad a nuestro Se\u00f1or Jesucristo ten\u00eda un alto costo, en su caso la c\u00e1rcel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El no se encontraba en prisi\u00f3n por ser un malhechor y delincuente, sino por el contrario por predicar el mensaje del evangelio con valent\u00eda en un tiempo en el cual hacerlo era un delito. Pero \u00bfQu\u00e9 era mas importante para Pablo? \u00bfObedecer a Dios o obedecer a los hombres? . En el coraz\u00f3n del ap\u00f3stol Pablo hab\u00eda espacio solo para una persona y ese era Dios. <br>\nEn esta condici\u00f3n y con su vivo ejemplo hace un llamado y suplica a todos los cristianos a que vivan como es digno de la vocaci\u00f3n con que fueron llamados. Fuimos llamados de la condenaci\u00f3n y la muerte eterna a una vida gloriosa en Cristo Jes\u00fas, fuimos llamados del mundo de las tinieblas al mundo de la luz, de hijos de ira a Hijos de Dios; de lejanos a causa de nuestro pecado a cercanos por la sangre de Cristo, de ciudadanos terrenales a ciudadanos celestiales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En consecuencia nuestro andar o estilo de vida debiera de reflejar nuestra fe y nuestra nueva condici\u00f3n en Cristo. somos llamados a vivir un estilo de vida que agrada a Dios, somos llamados a amar a Dios por encima de todo, somos llamados a amar a nuestro pr\u00f3jimo como a nosotros mismos, somos llamados a servir, evangelizar y discipular, somos llamados a seguir los pasos del maestro, somos llamados a ser cada uno de nosotros misioneros por la causa de Cristo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si pudi\u00e9ramos simplificar el texto, esta dir\u00eda lo siguiente \u201cya que sois cristianos, vivid como tal\u201d ser cristiano no es una serie de ritos religiosos que tienes que realizar cada semana, ser cristiano no es vestirte de morado con un crucifijo grande en el pecho, ser cristiano no es asunto de religi\u00f3n, ser cristiano es esencialmente vivir a Cristo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pablo era un modelo de esto, \u00e9l viv\u00eda a Cristo, el era un misionero de alma y coraz\u00f3n cuyo mensaje era acorde a su estilo de vida. \u00bfQu\u00e9 de nosotros? Sab\u00edan que cuando entregamos nuestra vida a nuestro Se\u00f1or Jesucristo, en ese mismo d\u00eda fuimos llamados a ser misioneros cada uno de nosotros, Jes\u00fas nos encomend\u00f3 una misi\u00f3n y esa es el de hacer disc\u00edpulos a todas las naciones. Esta misi\u00f3n no es solo tarea del pastor, de los di\u00e1conos o de los l\u00edderes de nuestra iglesia, esta es tarea de todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bf y donde es nuestro campo misionero? Puede ser en nuestro hogar, en nuestro vecindario, en nuestro centro de estudios o en nuestro trabajo, ah\u00ed es donde debemos de dar testimonio y levantar bien en alto el nombre de nuestro Se\u00f1or Jesucristo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;Paul Tinoco Huaraca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cYo pues, preso en el Se\u00f1or, os ruego que and\u00e9is como es digno de la vocaci\u00f3n con que fuisteis llamados,\u201d [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[765],"tags":[465,768,62,137],"class_list":["post-416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mi-cuaderno-espiritual","tag-dedicacion","tag-misionero","tag-misiones","tag-trabajo-misionero"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Misioneros Dedicados - #1 - Lifeword en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Misioneros Dedicados - #1 - Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"\u201cYo pues, preso en el Se\u00f1or, os ruego que and\u00e9is como es digno de la vocaci\u00f3n con que fuisteis llamados,\u201d [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-29T19:54:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-17T19:56:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lifeword\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lifeword\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/misioneros-dedicados-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/misioneros-dedicados-1\\\/\"},\"author\":{\"name\":\"lifeword\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\"},\"headline\":\"Misioneros Dedicados &#8211; #1\",\"datePublished\":\"2018-10-29T19:54:14+00:00\",\"dateModified\":\"2019-04-17T19:56:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/misioneros-dedicados-1\\\/\"},\"wordCount\":549,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/misioneros-dedicados-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/misioneros_dedicados.jpg\",\"keywords\":[\"dedicaci\u00f3n\",\"misionero\",\"misiones\",\"trabajo misionero\"],\"articleSection\":[\"Mi Cuaderno Espiritual\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/misioneros-dedicados-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/misioneros-dedicados-1\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/misioneros-dedicados-1\\\/\",\"name\":\"Misioneros Dedicados - #1 - Lifeword en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/misioneros-dedicados-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/misioneros-dedicados-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/misioneros_dedicados.jpg\",\"datePublished\":\"2018-10-29T19:54:14+00:00\",\"dateModified\":\"2019-04-17T19:56:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/misioneros-dedicados-1\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/misioneros-dedicados-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/misioneros-dedicados-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/misioneros_dedicados.jpg\",\"contentUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/misioneros_dedicados.jpg\",\"width\":280,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/misioneros-dedicados-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Misioneros Dedicados &#8211; #1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\",\"name\":\"Lifeword en Espa\u00f1ol\",\"description\":\"Palabras De Vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\",\"name\":\"lifeword\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"caption\":\"lifeword\"},\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/author\\\/lifeword\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Misioneros Dedicados - #1 - Lifeword en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/","og_locale":"es_ES","og_type":"article","og_title":"Misioneros Dedicados - #1 - Lifeword en Espa\u00f1ol","og_description":"\u201cYo pues, preso en el Se\u00f1or, os ruego que and\u00e9is como es digno de la vocaci\u00f3n con que fuisteis llamados,\u201d [&hellip;]","og_url":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/","og_site_name":"Lifeword en Espa\u00f1ol","article_published_time":"2018-10-29T19:54:14+00:00","article_modified_time":"2019-04-17T19:56:30+00:00","og_image":[{"width":280,"height":280,"url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg","type":"image\/jpeg"}],"author":"lifeword","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lifeword","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/#article","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/"},"author":{"name":"lifeword","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518"},"headline":"Misioneros Dedicados &#8211; #1","datePublished":"2018-10-29T19:54:14+00:00","dateModified":"2019-04-17T19:56:30+00:00","mainEntityOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/"},"wordCount":549,"commentCount":0,"image":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg","keywords":["dedicaci\u00f3n","misionero","misiones","trabajo misionero"],"articleSection":["Mi Cuaderno Espiritual"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/","url":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/","name":"Misioneros Dedicados - #1 - Lifeword en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/#primaryimage"},"image":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg","datePublished":"2018-10-29T19:54:14+00:00","dateModified":"2019-04-17T19:56:30+00:00","author":{"@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/#primaryimage","url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg","contentUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg","width":280,"height":280},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/misioneros-dedicados-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/spanish\/"},{"@type":"ListItem","position":2,"name":"Misioneros Dedicados &#8211; #1"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/spanish\/#website","url":"https:\/\/lifeword.org\/spanish\/","name":"Lifeword en Espa\u00f1ol","description":"Palabras De Vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518","name":"lifeword","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","caption":"lifeword"},"url":"https:\/\/lifeword.org\/spanish\/author\/lifeword\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg",280,280,false],"thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados-150x150.jpg",150,150,true],"medium":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg",280,280,false],"medium_large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg",280,280,false],"large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg",280,280,false],"1536x1536":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg",280,280,false],"2048x2048":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg",280,280,false],"post-thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados-264x168.jpg",264,168,true],"lifeword-detail-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg",280,280,false],"lifeword-slider-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg",280,280,false],"lifeword-list-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg",280,280,false],"gform-image-choice-sm":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg",280,280,false],"gform-image-choice-md":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg",280,280,false],"gform-image-choice-lg":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/misioneros_dedicados.jpg",280,280,false]},"uagb_author_info":{"display_name":"lifeword","author_link":"https:\/\/lifeword.org\/spanish\/author\/lifeword\/"},"uagb_comment_info":0,"uagb_excerpt":"\u201cYo pues, preso en el Se\u00f1or, os ruego que and\u00e9is como es digno de la vocaci\u00f3n con que fuisteis llamados,\u201d [&hellip;]","_links":{"self":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/comments?post=416"}],"version-history":[{"count":1,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/416\/revisions"}],"predecessor-version":[{"id":418,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/416\/revisions\/418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media\/417"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media?parent=416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/categories?post=416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/tags?post=416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}