{"id":414,"date":"2018-10-23T19:18:57","date_gmt":"2018-10-23T19:18:57","guid":{"rendered":"https:\/\/lifeword.org\/spanish\/?p=414"},"modified":"2019-04-17T19:20:23","modified_gmt":"2019-04-17T19:20:23","slug":"discipuladores-dinamicos-2","status":"publish","type":"post","link":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/","title":{"rendered":"Discipuladores Dinamicos &#8211; #2"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cEn esto es glorificado mi Padre, en que llev\u00e9is mucho fruto, y se\u00e1is as\u00ed mis disc\u00edpulos\u201d Juan 15:8 RVR1960<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuimos creados para glorificar a Dios, llevar una vida que de gloria y honra a nuestro Dios es el privilegio y el deber mas grande que tiene todo creyente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo podemos glorificar a Dios? Nuestro Se\u00f1or Jesucristo lo dice de una forma bien sencilla y pr\u00e1ctica: \u201cEn esto es glorificado mi Padre, en que llev\u00e9is mucho fruto y se\u00e1is as\u00ed mis disc\u00edpulos\u201d aqu\u00ed vemos dos cosas interesantes, la primera es que una de las caracter\u00edsticas de un disc\u00edpulo de Jes\u00fas es que produce fruto espiritual, y lo segundo que vemos es que Dios desea que produzcamos no uno ni dos, sino mucho fruto espiritual y para que as\u00ed sea, tenemos que esforzarnos y trabajar con el coraz\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 es un fruto espiritual? En las escrituras encontramos varias clases de fruto espiritual. En primer lugar, fruto espiritual son las actitudes espirituales que caracterizan a los creyentes G\u00e1latas 5:22 dice \u201cMas el fruto del Esp\u00edritu es amor, gozo, paz, paciencia, benignidad, bondad, fe, mansedumbre, templanza; contra tales cosas no hay ley\u201d mis amados hermanos debemos de dedicar tiempo en cultivar nuestro ser interior, lo que nosotros somos es mas importante que lo que nosotros hacemos, nuestra piedad es mas importante que nuestros dones y talentos, nuestra integridad es mas importante que nuestro ministerio, y nuestra alma y coraz\u00f3n es mas importante que el \u00e9xito y el tama\u00f1o de nuestra congregaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En segundo lugar un fruto espiritual es la alabanza a nuestro amado Dios. Hebreos 13:15 dice \u201cAs\u00ed que, ofrezcamos siempre a Dios, por medio de \u00e9l, sacrificio de alabanza, es decir, fruto de labios que confiesan su nombre\u201d cada d\u00eda debemos de alabar a nuestro Dios y debemos de hacerlo con el coraz\u00f3n, con entendimiento, con alegr\u00eda y gratitud por sus m\u00faltiples bondades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tercer lugar el amor sacrificial para satisfacer las necesidades de los dem\u00e1s, es llamado fruto espiritual. El ap\u00f3stol Pablo recolect\u00f3 una ofrenda para los necesitados en la iglesia en Jerusal\u00e9n, en referencia a esto escribi\u00f3 a los Romanos \u201cAs\u00ed que, cuando haya concluido esto, y les haya entregado este fruto, pasar\u00e9 entre vosotros rumbo a Espa\u00f1a\u201d Nuestro amor a Dios se evidencia por medio de nuestro amor a las dem\u00e1s personas. Y si alguien esta pasando alguna necesidad \u00bfC\u00f3mo podemos cerrar nuestro coraz\u00f3n a ello? debemos de tener un coraz\u00f3n que este atento a las necesidades de las dem\u00e1s personas y ver como podemos suplir cada una de ellas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y por \u00faltimo la Biblia habla de fruto espiritual en relaci\u00f3n a los nuevos creyentes. Pablo expres\u00f3 lo siguiente a la iglesia en Roma \u201cNo quiero, hermanos, que ignor\u00e9is que muchas veces me he propuesto ir a vosotros (pero hasta ahora he sido estorbado), para tener tambi\u00e9n entre vosotros alg\u00fan fruto, como entre los dem\u00e1s gentiles\u201d Pablo deseaba ganar personas para Cristo cuando este en Roma, el deseaba tener un fruto espiritual entre ellos, as\u00ed como un \u00e1rbol de manzanas da manzanas y un \u00e1rbol de naranjas da naranjas, el fruto de un disc\u00edpulo de Jes\u00fas es otro disc\u00edpulo, para que ello suceda tenemos que invertir nuestra vida en la vida de las dem\u00e1s personas, creo que no hay mejor forma de mostrar nuestro amor al pr\u00f3jimo que invirtiendo nuestro tiempo, dinero y recursos en el bienestar de los dem\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un disc\u00edpulo din\u00e1mico hace esto, el no se queda sentado en la iglesia esperando a que la gente llegue, \u00e9l va en busca del perdido, \u00e9l comparte con valent\u00eda y sin temor el evangelio, y una vez alguien se convierte, \u00e9l dedica horas, d\u00edas y a\u00f1os en hacer que ese peque\u00f1o bebe espiritual crezca por medio de su ense\u00f1anza y por medio de su testimonio, el produce fruto y no se conforma con discipular a uno, sino va en busca de otro y otro y otro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dios nos ayude a cada uno de nosotros a ser disc\u00edpulos din\u00e1micos, disc\u00edpulos que con su vida dan gloria y honra a Dios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;Paul Tinoco Huaraca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEn esto es glorificado mi Padre, en que llev\u00e9is mucho fruto, y se\u00e1is as\u00ed mis disc\u00edpulos\u201d Juan 15:8 RVR1960 Fuimos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":412,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[765],"tags":[25,194],"class_list":["post-414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mi-cuaderno-espiritual","tag-discipulado","tag-discipular"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Discipuladores Dinamicos - #2 - Lifeword en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Discipuladores Dinamicos - #2 - Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"\u201cEn esto es glorificado mi Padre, en que llev\u00e9is mucho fruto, y se\u00e1is as\u00ed mis disc\u00edpulos\u201d Juan 15:8 RVR1960 Fuimos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-23T19:18:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-17T19:20:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lifeword\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lifeword\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/discipuladores-dinamicos-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/discipuladores-dinamicos-2\\\/\"},\"author\":{\"name\":\"lifeword\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\"},\"headline\":\"Discipuladores Dinamicos &#8211; #2\",\"datePublished\":\"2018-10-23T19:18:57+00:00\",\"dateModified\":\"2019-04-17T19:20:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/discipuladores-dinamicos-2\\\/\"},\"wordCount\":724,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/discipuladores-dinamicos-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/discipuladores_dinamicos.jpg\",\"keywords\":[\"discipulado\",\"discipular\"],\"articleSection\":[\"Mi Cuaderno Espiritual\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/discipuladores-dinamicos-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/discipuladores-dinamicos-2\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/discipuladores-dinamicos-2\\\/\",\"name\":\"Discipuladores Dinamicos - #2 - Lifeword en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/discipuladores-dinamicos-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/discipuladores-dinamicos-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/discipuladores_dinamicos.jpg\",\"datePublished\":\"2018-10-23T19:18:57+00:00\",\"dateModified\":\"2019-04-17T19:20:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/discipuladores-dinamicos-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/discipuladores-dinamicos-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/discipuladores-dinamicos-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/discipuladores_dinamicos.jpg\",\"contentUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/discipuladores_dinamicos.jpg\",\"width\":280,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/discipuladores-dinamicos-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Discipuladores Dinamicos &#8211; #2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\",\"name\":\"Lifeword en Espa\u00f1ol\",\"description\":\"Palabras De Vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\",\"name\":\"lifeword\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"caption\":\"lifeword\"},\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/author\\\/lifeword\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Discipuladores Dinamicos - #2 - Lifeword en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/","og_locale":"es_ES","og_type":"article","og_title":"Discipuladores Dinamicos - #2 - Lifeword en Espa\u00f1ol","og_description":"\u201cEn esto es glorificado mi Padre, en que llev\u00e9is mucho fruto, y se\u00e1is as\u00ed mis disc\u00edpulos\u201d Juan 15:8 RVR1960 Fuimos [&hellip;]","og_url":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/","og_site_name":"Lifeword en Espa\u00f1ol","article_published_time":"2018-10-23T19:18:57+00:00","article_modified_time":"2019-04-17T19:20:23+00:00","og_image":[{"width":280,"height":280,"url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg","type":"image\/jpeg"}],"author":"lifeword","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lifeword","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/#article","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/"},"author":{"name":"lifeword","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518"},"headline":"Discipuladores Dinamicos &#8211; #2","datePublished":"2018-10-23T19:18:57+00:00","dateModified":"2019-04-17T19:20:23+00:00","mainEntityOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/"},"wordCount":724,"commentCount":0,"image":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg","keywords":["discipulado","discipular"],"articleSection":["Mi Cuaderno Espiritual"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/","url":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/","name":"Discipuladores Dinamicos - #2 - Lifeword en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/#primaryimage"},"image":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg","datePublished":"2018-10-23T19:18:57+00:00","dateModified":"2019-04-17T19:20:23+00:00","author":{"@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/#primaryimage","url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg","contentUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg","width":280,"height":280},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/discipuladores-dinamicos-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/spanish\/"},{"@type":"ListItem","position":2,"name":"Discipuladores Dinamicos &#8211; #2"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/spanish\/#website","url":"https:\/\/lifeword.org\/spanish\/","name":"Lifeword en Espa\u00f1ol","description":"Palabras De Vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518","name":"lifeword","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","caption":"lifeword"},"url":"https:\/\/lifeword.org\/spanish\/author\/lifeword\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg",280,280,false],"thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos-150x150.jpg",150,150,true],"medium":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg",280,280,false],"medium_large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg",280,280,false],"large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg",280,280,false],"1536x1536":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg",280,280,false],"2048x2048":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg",280,280,false],"post-thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos-264x168.jpg",264,168,true],"lifeword-detail-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg",280,280,false],"lifeword-slider-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg",280,280,false],"lifeword-list-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg",280,280,false],"gform-image-choice-sm":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg",280,280,false],"gform-image-choice-md":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg",280,280,false],"gform-image-choice-lg":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/discipuladores_dinamicos.jpg",280,280,false]},"uagb_author_info":{"display_name":"lifeword","author_link":"https:\/\/lifeword.org\/spanish\/author\/lifeword\/"},"uagb_comment_info":0,"uagb_excerpt":"\u201cEn esto es glorificado mi Padre, en que llev\u00e9is mucho fruto, y se\u00e1is as\u00ed mis disc\u00edpulos\u201d Juan 15:8 RVR1960 Fuimos [&hellip;]","_links":{"self":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/comments?post=414"}],"version-history":[{"count":1,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/414\/revisions"}],"predecessor-version":[{"id":415,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/414\/revisions\/415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media\/412"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media?parent=414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/categories?post=414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/tags?post=414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}