{"id":373,"date":"2018-10-01T21:51:11","date_gmt":"2018-10-01T21:51:11","guid":{"rendered":"https:\/\/lifeword.org\/spanish\/?p=373"},"modified":"2019-04-16T21:55:46","modified_gmt":"2019-04-16T21:55:46","slug":"nos-hemos-visto-en-el-espejo-ultimamente","status":"publish","type":"post","link":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/","title":{"rendered":"\u00bfNos hemos visto en el espejo \u00faltimamente?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El prop\u00f3sito de un espejo es para vernos. En \u00e9l podemos ver lo que otras personas est\u00e1n viendo al mirarnos. En \u00e9l podemos ver nuestras imperfecciones con el fin de hacer algunos arreglos, si es que se puede.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El prop\u00f3sito de un espejo es para vernos. En \u00e9l podemos ver lo que otras personas est\u00e1n viendo al mirarnos. En \u00e9l podemos ver nuestras imperfecciones con el fin de hacer algunos arreglos, si es que se puede.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mejor espejo que tenemos es La Palabra de Dios. Al vernos en la Palabra, nos damos cuenta de nuestras imperfecciones, y podemos venir a Dios y hacer lo que nos dice, con el fin de realizar mejoras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Efesios 3:20-21 dice, \u201cY a Aquel que es poderoso para hacer todas las cosas mucho m\u00e1s abundantemente de lo que pedimos o entendemos, seg\u00fan el poder que act\u00faa en nosotros, a \u00c9l sea gloria en la iglesia en Cristo Jes\u00fas por todas las edades, por los siglos de los siglos. Am\u00e9n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al vernos en el espejo de Efesios 3:20 y21, \u00bfqu\u00e9 vemos? \u00bfVemos a una Iglesia esforz\u00e1ndose a traer gloria a Dios? \u00bfVemos a una Iglesia que est\u00e1 en Cristo, dedicada al pi\u00e9 de la letra a la misi\u00f3n que le fue encomendada? \u00bfVemos una Iglesia que est\u00e1 experimentando el poder de Dios, trabajando a trav\u00e9s de ella? Si no vemos estas cosas; ha llegado la hora de hacer algo en cuanto a ello.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(1) La Iglesia es para gloria de Dios. Nuestro texto dice que Dios debe recibir gloria en la Iglesia \u201cpor todas las edades, por los siglos de los siglos\u201d. Esto significa que la Iglesia nunca se ha tratado de nosotros, sino de \u00c9l. No es asunto de la Iglesia buscar lo que le gusta a las personas, para luego hacer todo lo posible por prove\u00e9rselos. No tenemos que cambiar de tecnolog\u00eda, m\u00fasica, etc., para que vengan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es cierto que queremos que los que asistan a nuestra Iglesia est\u00e9n comodos, y que les guste lo que hacemos; pero, si vienen y nunca llegan a conocer a Dios, debido a que \u00c9l no se present\u00f3, porque no se trat\u00f3 de \u00c9l, sino de la gente, \u00bfde qu\u00e9 sirvi\u00f3?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(2) Iglesia que no est\u00e1 en Cristo, no trae gloria a Dios. Nuestro texto dice, \u201ca \u00c9l sea gloria en la iglesia EN CRISTO JES\u00daS\u201d. Una Iglesia que no est\u00e1 en Jes\u00fas, viviendo de acuerdo a Sus ense\u00f1anzas, cumpliendo las cosas por la cual fue llamada, no puede traer gloria a Dios. Hay una infinidad de Iglesias el d\u00eda de hoy; pero, son muy pocas las que realmente traen gloria a Dios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo es que Jes\u00fas trae gloria a Dios? Jes\u00fas trae gloria a Dios, porque Su voluntad es hacer la voluntad del Padre. En Juan 5:30 Jes\u00fas dice, \u201cNo puedo yo hacer nada por m\u00ed mismo; seg\u00fan oigo, as\u00ed juzgo; y mi juicio es justo, porque no busco mi voluntad, sino la voluntad del que me envi\u00f3, la del Padre.\u201d Noten que Jes\u00fas dijo que no pod\u00eda hacer nada por s\u00ed mismo. Puso Su completa confianza en Dios, para serle obediente en todo lo que pidi\u00f3 de \u00c9l. Lo de caminar sobre el agua, dar vista a los ciegos, resucitar a los muertos, y resucitar al tercer d\u00eda\u2026Todo eso fue el Padre. Jes\u00fas solo fue obediente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El creer que podemos sin \u00c9l, no le trae gloria. Todas las cosas que no hacemos (asistir al templo, Centro De Acci\u00f3n; discipular, usar las cuatro armas espirituales etc.), es porque pensamos que podemos ganar esta batalla sin \u00c9l. Esta actitud no trae gloria a Dios. Mas bien le ofende.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(3) Iglesia que no trae gloria a Dios, no experimentar\u00e1 Su poder. Nuestro texto nos se\u00f1ala que Dios es \u201cpoderoso para hacer todas las cosas mucho m\u00e1s abundantemente de lo que pedimos o entendemos\u201d, mas nosotros nunca lo experimentaremos, porque pensamos que se trata de nosotros, en vez de \u00c9l.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando nos miramos en el espejo de la Palabra, no debemos ver nuestro reflejo. \u00a1Debemos ver a Jes\u00fas! Si no vemos a Jes\u00fas, tampoco veremos el poder de Dios. Nuestra relaci\u00f3n con el Padre, es a trav\u00e9s de Jes\u00fas. \u00c9l mismo nos dijo que nadie vendr\u00eda al Padre, sino por \u00c9l. Observemos la oraci\u00f3n que hizo al Padre antes de regresar al cielo. \u201cMas no ruego solamente por \u00e9stos, sino tambi\u00e9n por los que han de creer en m\u00ed por la palabra de ellos, para que todos sean uno; como t\u00fa, oh Padre, en m\u00ed, y yo en ti, que tambi\u00e9n ellos sean uno en nosotros; para que el mundo crea que t\u00fa me enviaste. La gloria que me diste, yo les he dado, para que sean uno, as\u00ed como nosotros somos uno. Yo en ellos, y t\u00fa en m\u00ed, para que sean perfectos en unidad, para que el mundo conozca que t\u00fa me enviaste, y que los has amado a ellos como tambi\u00e9n a m\u00ed me has amado\u201d (Juan 17:20-23).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfObservaste el \u00e9nfasis que Jes\u00fas hace al repetir, \u201cT\u00fa en m\u00ed\u201d y \u201cYo en ellos\u201d. \u00bfPor qu\u00e9? Porque sin el Padre en \u00c9l, y sin \u00c9l en nosotros, no habr\u00e1 poder para vencer. Conste que podemos hacer creer a los dem\u00e1s que el poder de Dios fluye a trav\u00e9s de nosotros. Pero, nuestra lucha no es con ellos. Es con el diablo, y sus demonios, y ellos conocen la verdad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermano, es el poder de Dios y Su amor lo que salvar\u00e1 al mundo. Ojala al vernos en el espejo, vemos una Iglesia dedicada a la misi\u00f3n que Jes\u00fas nos ha encomendado y no un Club Social, donde venimos a entretenernos por un rato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amigo, la Iglesia no est\u00e1 aqu\u00ed para entretenerte. Est\u00e1 aqu\u00ed para intentar rescatar tu alma del infierno. Dios te ama. La Iglesia est\u00e1 aqu\u00ed para hac\u00e9rtelo saber.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;Andres Tinoco<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El prop\u00f3sito de un espejo es para vernos. En \u00e9l podemos ver lo que otras personas est\u00e1n viendo al mirarnos. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":374,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[765],"tags":[],"class_list":["post-373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mi-cuaderno-espiritual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfNos hemos visto en el espejo \u00faltimamente? - Lifeword en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfNos hemos visto en el espejo \u00faltimamente? - Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"El prop\u00f3sito de un espejo es para vernos. En \u00e9l podemos ver lo que otras personas est\u00e1n viendo al mirarnos. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-01T21:51:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-16T21:55:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1575\" \/>\n\t<meta property=\"og:image:height\" content=\"1575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lifeword\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lifeword\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/nos-hemos-visto-en-el-espejo-ultimamente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/nos-hemos-visto-en-el-espejo-ultimamente\\\/\"},\"author\":{\"name\":\"lifeword\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\"},\"headline\":\"\u00bfNos hemos visto en el espejo \u00faltimamente?\",\"datePublished\":\"2018-10-01T21:51:11+00:00\",\"dateModified\":\"2019-04-16T21:55:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/nos-hemos-visto-en-el-espejo-ultimamente\\\/\"},\"wordCount\":1016,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/nos-hemos-visto-en-el-espejo-ultimamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/espejo.jpg\",\"articleSection\":[\"Mi Cuaderno Espiritual\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/nos-hemos-visto-en-el-espejo-ultimamente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/nos-hemos-visto-en-el-espejo-ultimamente\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/nos-hemos-visto-en-el-espejo-ultimamente\\\/\",\"name\":\"\u00bfNos hemos visto en el espejo \u00faltimamente? - Lifeword en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/nos-hemos-visto-en-el-espejo-ultimamente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/nos-hemos-visto-en-el-espejo-ultimamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/espejo.jpg\",\"datePublished\":\"2018-10-01T21:51:11+00:00\",\"dateModified\":\"2019-04-16T21:55:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/nos-hemos-visto-en-el-espejo-ultimamente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/nos-hemos-visto-en-el-espejo-ultimamente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/nos-hemos-visto-en-el-espejo-ultimamente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/espejo.jpg\",\"contentUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/espejo.jpg\",\"width\":1575,\"height\":1575},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/nos-hemos-visto-en-el-espejo-ultimamente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfNos hemos visto en el espejo \u00faltimamente?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\",\"name\":\"Lifeword en Espa\u00f1ol\",\"description\":\"Palabras De Vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\",\"name\":\"lifeword\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"caption\":\"lifeword\"},\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/author\\\/lifeword\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfNos hemos visto en el espejo \u00faltimamente? - Lifeword en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfNos hemos visto en el espejo \u00faltimamente? - Lifeword en Espa\u00f1ol","og_description":"El prop\u00f3sito de un espejo es para vernos. En \u00e9l podemos ver lo que otras personas est\u00e1n viendo al mirarnos. [&hellip;]","og_url":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/","og_site_name":"Lifeword en Espa\u00f1ol","article_published_time":"2018-10-01T21:51:11+00:00","article_modified_time":"2019-04-16T21:55:46+00:00","og_image":[{"width":1575,"height":1575,"url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo.jpg","type":"image\/jpeg"}],"author":"lifeword","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lifeword","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/#article","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/"},"author":{"name":"lifeword","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518"},"headline":"\u00bfNos hemos visto en el espejo \u00faltimamente?","datePublished":"2018-10-01T21:51:11+00:00","dateModified":"2019-04-16T21:55:46+00:00","mainEntityOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/"},"wordCount":1016,"commentCount":0,"image":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo.jpg","articleSection":["Mi Cuaderno Espiritual"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/","url":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/","name":"\u00bfNos hemos visto en el espejo \u00faltimamente? - Lifeword en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/#primaryimage"},"image":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo.jpg","datePublished":"2018-10-01T21:51:11+00:00","dateModified":"2019-04-16T21:55:46+00:00","author":{"@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/#primaryimage","url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo.jpg","contentUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo.jpg","width":1575,"height":1575},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/nos-hemos-visto-en-el-espejo-ultimamente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/spanish\/"},{"@type":"ListItem","position":2,"name":"\u00bfNos hemos visto en el espejo \u00faltimamente?"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/spanish\/#website","url":"https:\/\/lifeword.org\/spanish\/","name":"Lifeword en Espa\u00f1ol","description":"Palabras De Vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518","name":"lifeword","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","caption":"lifeword"},"url":"https:\/\/lifeword.org\/spanish\/author\/lifeword\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo.jpg",1575,1575,false],"thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo-150x150.jpg",150,150,true],"medium":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo-300x300.jpg",300,300,true],"medium_large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo-768x768.jpg",768,768,true],"large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo-1024x1024.jpg",1024,1024,true],"1536x1536":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo.jpg",1536,1536,false],"2048x2048":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo.jpg",1575,1575,false],"post-thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo-264x168.jpg",264,168,true],"lifeword-detail-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo-775x437.jpg",775,437,true],"lifeword-slider-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo-562x357.jpg",562,357,true],"lifeword-list-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo-600x480.jpg",600,480,true],"gform-image-choice-sm":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo.jpg",300,300,false],"gform-image-choice-md":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo.jpg",400,400,false],"gform-image-choice-lg":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/espejo.jpg",600,600,false]},"uagb_author_info":{"display_name":"lifeword","author_link":"https:\/\/lifeword.org\/spanish\/author\/lifeword\/"},"uagb_comment_info":0,"uagb_excerpt":"El prop\u00f3sito de un espejo es para vernos. En \u00e9l podemos ver lo que otras personas est\u00e1n viendo al mirarnos. [&hellip;]","_links":{"self":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/comments?post=373"}],"version-history":[{"count":1,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/373\/revisions"}],"predecessor-version":[{"id":375,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/373\/revisions\/375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media\/374"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media?parent=373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/categories?post=373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/tags?post=373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}