{"id":363,"date":"2018-09-11T21:38:13","date_gmt":"2018-09-11T21:38:13","guid":{"rendered":"https:\/\/lifeword.org\/spanish\/?p=363"},"modified":"2019-04-16T21:39:13","modified_gmt":"2019-04-16T21:39:13","slug":"glorificando-a-dios-en-todo-2","status":"publish","type":"post","link":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/","title":{"rendered":"Glorificando A Dios En Todo &#8211; #2"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cProclamad entre las naciones su gloria, En todos los pueblos sus maravillas.\u201d \u202d\u202dSalmos\u202c \u202d96:3\u202c \u202dRVR1960\u202c\u202c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como cristianos tenemos el deber de proclamar en todo tiempo y en todo lugar su gloria. Comenzando desde nuestro hogar, seguido por nuestro vecindario, despues nuestra ciudad, luego nuestro pais y por \u00faltimo cada rincon de nuestro mundo deben de oir las maravillas que hizo nuestro gran Dios y las maravillas que \u00e9l contin\u00faa haciendo en las vidas de cada uno de nosotros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra forma de hablar, nuestra forma de comportarnos, nuestra forma de vestir y nuestro trato a los dem\u00e1s, todo, absolutamente todo de nosotros debe de dar gloria a nuestro Dios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joe Stowell conto lo siguiente \u201cMe encanta un video de YouTube, donde un grupo de personas en el patio de comidas de un centro comercial y en medio de sus rutinas fue repentinamente interrumpido por alguien que empez\u00f3 a cantar el Aleluya de H\u00e4ndel. Para sorpresa de todos, alguien se puso de pie y se uni\u00f3 al canto, y despu\u00e9s otro y otro m\u00e1s. Al poco tiempo, el lugar resonaba con los inolvidables acordes de esta obra maestra de la m\u00fasica. Una empresa local de \u00f3pera hab\u00eda ubicado a sus cantantes en lugares estrat\u00e9gicos, para que pudieran interpolar con gozo la gloria de Dios en la vida diaria de los compradores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada vez que miro el video, se me caen las l\u00e1grimas. Me recuerda que somos espec\u00edficamente llamados a glorificar al Se\u00f1or en la cotidianidad de nuestro mundo mediante los bellos acordes de una vida de semejanza a \u00c9l. Lo hacemos al incorporar intencionalmente la gracia de Dios en una situaci\u00f3n para que alguien que no lo merece tenga una segunda oportunidad, al compartir el amor de Cristo con alg\u00fan necesitado, al ser las manos de Jes\u00fas para levantar a un amigo agotado o apaciguar una situaci\u00f3n ca\u00f3tica y confusa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El salmista nos recuerda que tenemos el privilegio sublime y santo de declarar \u00abentre las naciones su gloria, en todos los pueblos sus maravillas\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saben vemos sus maravillas en todo lo creado, desde una peque\u00f1a gota de agua hasta el vasto universo, todo es obra perfecta de sus manos, pero lo que mas me causa admiraci\u00f3n es la belleza del salvador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien dijo John Gill \u201c\u00a1Qu\u00e9 persona tan maravillosa es Cristo, porque \u00c9l es Dios manifestado en la carne! \u00a1Qu\u00e9 maravilloso amor ha mostrado en su encamaci\u00f3n, obediencia, sufrimientos y muerte; qu\u00e9 asombrosos milagros ha obrado, y qu\u00e9 maravillosa obra ha ejecutado; la obra de nuestra redenci\u00f3n, el asombro de los hombres y de los \u00e1ngeles! Proclama su maravillosa resurrecci\u00f3n de los muertos, su ascensi\u00f3n al cielo, donde ahora est\u00e1 sentado a la diestra de Dios e intercede por su pueblo; la maravillosa efusi\u00f3n de su Esp\u00edritu, y las conquistas de su gracia, y el engrandecimiento de su reino en el mundo; as\u00ed como las maravillas que ser\u00e1n obradas por El cuando aparezca por segunda vez, cuando los muertos ser\u00e1n resucitados y juzgados todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;Paul Tinoco Huaraca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cProclamad entre las naciones su gloria, En todos los pueblos sus maravillas.\u201d \u202d\u202dSalmos\u202c \u202d96:3\u202c \u202dRVR1960\u202c\u202c Como cristianos tenemos el deber [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":361,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[765],"tags":[],"class_list":["post-363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mi-cuaderno-espiritual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Glorificando A Dios En Todo - #2 - Lifeword en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Glorificando A Dios En Todo - #2 - Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"\u201cProclamad entre las naciones su gloria, En todos los pueblos sus maravillas.\u201d \u202d\u202dSalmos\u202c \u202d96:3\u202c \u202dRVR1960\u202c\u202c Como cristianos tenemos el deber [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-11T21:38:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-16T21:39:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1575\" \/>\n\t<meta property=\"og:image:height\" content=\"1575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lifeword\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lifeword\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-2\\\/\"},\"author\":{\"name\":\"lifeword\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\"},\"headline\":\"Glorificando A Dios En Todo &#8211; #2\",\"datePublished\":\"2018-09-11T21:38:13+00:00\",\"dateModified\":\"2019-04-16T21:39:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-2\\\/\"},\"wordCount\":526,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/06_glorificando_a_Dios_en_todo.jpg\",\"articleSection\":[\"Mi Cuaderno Espiritual\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-2\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-2\\\/\",\"name\":\"Glorificando A Dios En Todo - #2 - Lifeword en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/06_glorificando_a_Dios_en_todo.jpg\",\"datePublished\":\"2018-09-11T21:38:13+00:00\",\"dateModified\":\"2019-04-16T21:39:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/06_glorificando_a_Dios_en_todo.jpg\",\"contentUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/06_glorificando_a_Dios_en_todo.jpg\",\"width\":1575,\"height\":1575},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glorificando A Dios En Todo &#8211; #2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\",\"name\":\"Lifeword en Espa\u00f1ol\",\"description\":\"Palabras De Vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\",\"name\":\"lifeword\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"caption\":\"lifeword\"},\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/author\\\/lifeword\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Glorificando A Dios En Todo - #2 - Lifeword en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/","og_locale":"es_ES","og_type":"article","og_title":"Glorificando A Dios En Todo - #2 - Lifeword en Espa\u00f1ol","og_description":"\u201cProclamad entre las naciones su gloria, En todos los pueblos sus maravillas.\u201d \u202d\u202dSalmos\u202c \u202d96:3\u202c \u202dRVR1960\u202c\u202c Como cristianos tenemos el deber [&hellip;]","og_url":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/","og_site_name":"Lifeword en Espa\u00f1ol","article_published_time":"2018-09-11T21:38:13+00:00","article_modified_time":"2019-04-16T21:39:13+00:00","og_image":[{"width":1575,"height":1575,"url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg","type":"image\/jpeg"}],"author":"lifeword","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lifeword","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/#article","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/"},"author":{"name":"lifeword","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518"},"headline":"Glorificando A Dios En Todo &#8211; #2","datePublished":"2018-09-11T21:38:13+00:00","dateModified":"2019-04-16T21:39:13+00:00","mainEntityOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/"},"wordCount":526,"commentCount":0,"image":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg","articleSection":["Mi Cuaderno Espiritual"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/","url":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/","name":"Glorificando A Dios En Todo - #2 - Lifeword en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/#primaryimage"},"image":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg","datePublished":"2018-09-11T21:38:13+00:00","dateModified":"2019-04-16T21:39:13+00:00","author":{"@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/#primaryimage","url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg","contentUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg","width":1575,"height":1575},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/spanish\/"},{"@type":"ListItem","position":2,"name":"Glorificando A Dios En Todo &#8211; #2"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/spanish\/#website","url":"https:\/\/lifeword.org\/spanish\/","name":"Lifeword en Espa\u00f1ol","description":"Palabras De Vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518","name":"lifeword","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","caption":"lifeword"},"url":"https:\/\/lifeword.org\/spanish\/author\/lifeword\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg",1575,1575,false],"thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-150x150.jpg",150,150,true],"medium":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-300x300.jpg",300,300,true],"medium_large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-768x768.jpg",768,768,true],"large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-1024x1024.jpg",1024,1024,true],"1536x1536":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg",1536,1536,false],"2048x2048":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg",1575,1575,false],"post-thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-264x168.jpg",264,168,true],"lifeword-detail-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-775x437.jpg",775,437,true],"lifeword-slider-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-562x357.jpg",562,357,true],"lifeword-list-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-600x480.jpg",600,480,true],"gform-image-choice-sm":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg",300,300,false],"gform-image-choice-md":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg",400,400,false],"gform-image-choice-lg":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg",600,600,false]},"uagb_author_info":{"display_name":"lifeword","author_link":"https:\/\/lifeword.org\/spanish\/author\/lifeword\/"},"uagb_comment_info":0,"uagb_excerpt":"\u201cProclamad entre las naciones su gloria, En todos los pueblos sus maravillas.\u201d \u202d\u202dSalmos\u202c \u202d96:3\u202c \u202dRVR1960\u202c\u202c Como cristianos tenemos el deber [&hellip;]","_links":{"self":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/comments?post=363"}],"version-history":[{"count":1,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/363\/revisions"}],"predecessor-version":[{"id":364,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/363\/revisions\/364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media\/361"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media?parent=363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/categories?post=363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/tags?post=363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}