{"id":360,"date":"2018-09-10T21:31:29","date_gmt":"2018-09-10T21:31:29","guid":{"rendered":"https:\/\/lifeword.org\/spanish\/?p=360"},"modified":"2019-04-16T21:33:04","modified_gmt":"2019-04-16T21:33:04","slug":"glorificando-a-dios-en-todo-1","status":"publish","type":"post","link":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/","title":{"rendered":"Glorificando A Dios En Todo &#8211; #1"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cSi, pues, com\u00e9is o beb\u00e9is, o hac\u00e9is otra cosa, hacedlo todo para la gloria de Dios.\u201d \u202d\u202d1 Corintios\u202c \u202d10:31\u202c \u202dRVR1960\u202c\u202c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ap\u00f3stol Pablo exhorta a los Corintios a que en las actividades b\u00e1sicas de la vida como el comer o el beber, asi como en cualquier cosa que hagamos en nuestro diario vivir, debemos de buscar honrar y glorificar a nuestro Dios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un peri\u00f3dico importante de los Estados Unidos denomin\u00f3 a Christopher Parkening: \u00abel guitarrista m\u00e1s virtuoso de nuestros d\u00edas, ya que combina un profundo discernimiento musical con un completo dominio t\u00e9cnico de su instrumento\u00bb. Sin embargo, hubo una \u00e9poca cuando Parkening dej\u00f3 de tocar la guitarra profesionalmente. En el cl\u00edmax de su carrera como guitarrista cl\u00e1sico, a los 30 a\u00f1os, se retir\u00f3, compr\u00f3 un rancho en Montana y pasaba los d\u00edas pescando con mosca. No obstante, este retiro temprano no le brind\u00f3 la satisfacci\u00f3n que anhelaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s tarde, mientras visitaba California, lo invitaron a una iglesia, donde oy\u00f3 una clara presentaci\u00f3n del evangelio. Respecto a eso, escribi\u00f3: \u00abEsa noche me acost\u00e9 y no pude dormir, quebrantado por mis pecados \u2026 Hab\u00eda vivido de una manera muy ego\u00edsta y eso no me hab\u00eda hecho feliz\u2026 Fue entonces cuando le ped\u00ed a Jesucristo que entrara en mi vida, para que fuera mi Salvador y Se\u00f1or. Por primera vez en la vida, recuerdo haberle dicho: \u201cSe\u00f1or, lo que quieras que haga con mi vida, eso har\u00e9\u201d. Nuevamente volvi\u00f3 a tocar la guitarra pero ahora motivado por el deseo de glorificar a Dios en su vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo mismo paso con Johann Sebasti\u00e1n Bach, quien fue uno de los m\u00e1s grandes m\u00fasicos de la historia, \u00e9l escrib\u00eda las siglas \u201cS.D.G.\u201d al inicio de todas sus partituras. Esto significaba \u201cSolo a Dios la gloria\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 de nosotros? Sab\u00edan que una de las razones por la cual Dios dijo que nuestras mejores obras eran como trapos sucios de inmundicia, es porque detr\u00e1s de toda esa buena obra no se encuentra la gloria de Dios, sino la gloria del hombre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hacer todo para la gloria de Dios es hacerlo con excelencia, con integridad, acorde a su palabra y a su voluntad, es hacerlo con el fin de que su nombre sea exaltado y todo el mundo reconozca que el es un Dios bueno, grande y maravilloso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;Paul Tinoco Huaraca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSi, pues, com\u00e9is o beb\u00e9is, o hac\u00e9is otra cosa, hacedlo todo para la gloria de Dios.\u201d \u202d\u202d1 Corintios\u202c \u202d10:31\u202c \u202dRVR1960\u202c\u202c [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":361,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[765],"tags":[],"class_list":["post-360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mi-cuaderno-espiritual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Glorificando A Dios En Todo - #1 - Lifeword en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Glorificando A Dios En Todo - #1 - Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"\u201cSi, pues, com\u00e9is o beb\u00e9is, o hac\u00e9is otra cosa, hacedlo todo para la gloria de Dios.\u201d \u202d\u202d1 Corintios\u202c \u202d10:31\u202c \u202dRVR1960\u202c\u202c [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-10T21:31:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-16T21:33:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1575\" \/>\n\t<meta property=\"og:image:height\" content=\"1575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lifeword\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lifeword\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-1\\\/\"},\"author\":{\"name\":\"lifeword\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\"},\"headline\":\"Glorificando A Dios En Todo &#8211; #1\",\"datePublished\":\"2018-09-10T21:31:29+00:00\",\"dateModified\":\"2019-04-16T21:33:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-1\\\/\"},\"wordCount\":413,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/06_glorificando_a_Dios_en_todo.jpg\",\"articleSection\":[\"Mi Cuaderno Espiritual\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-1\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-1\\\/\",\"name\":\"Glorificando A Dios En Todo - #1 - Lifeword en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/06_glorificando_a_Dios_en_todo.jpg\",\"datePublished\":\"2018-09-10T21:31:29+00:00\",\"dateModified\":\"2019-04-16T21:33:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-1\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/06_glorificando_a_Dios_en_todo.jpg\",\"contentUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/04\\\/06_glorificando_a_Dios_en_todo.jpg\",\"width\":1575,\"height\":1575},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/mi-cuaderno-espiritual\\\/glorificando-a-dios-en-todo-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glorificando A Dios En Todo &#8211; #1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\",\"name\":\"Lifeword en Espa\u00f1ol\",\"description\":\"Palabras De Vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/f479cc575d11904ff91d030f0bbb0518\",\"name\":\"lifeword\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g\",\"caption\":\"lifeword\"},\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/author\\\/lifeword\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Glorificando A Dios En Todo - #1 - Lifeword en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/","og_locale":"es_ES","og_type":"article","og_title":"Glorificando A Dios En Todo - #1 - Lifeword en Espa\u00f1ol","og_description":"\u201cSi, pues, com\u00e9is o beb\u00e9is, o hac\u00e9is otra cosa, hacedlo todo para la gloria de Dios.\u201d \u202d\u202d1 Corintios\u202c \u202d10:31\u202c \u202dRVR1960\u202c\u202c [&hellip;]","og_url":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/","og_site_name":"Lifeword en Espa\u00f1ol","article_published_time":"2018-09-10T21:31:29+00:00","article_modified_time":"2019-04-16T21:33:04+00:00","og_image":[{"width":1575,"height":1575,"url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg","type":"image\/jpeg"}],"author":"lifeword","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lifeword","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/#article","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/"},"author":{"name":"lifeword","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518"},"headline":"Glorificando A Dios En Todo &#8211; #1","datePublished":"2018-09-10T21:31:29+00:00","dateModified":"2019-04-16T21:33:04+00:00","mainEntityOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/"},"wordCount":413,"commentCount":0,"image":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg","articleSection":["Mi Cuaderno Espiritual"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/","url":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/","name":"Glorificando A Dios En Todo - #1 - Lifeword en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/#primaryimage"},"image":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg","datePublished":"2018-09-10T21:31:29+00:00","dateModified":"2019-04-16T21:33:04+00:00","author":{"@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/#primaryimage","url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg","contentUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg","width":1575,"height":1575},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/spanish\/mi-cuaderno-espiritual\/glorificando-a-dios-en-todo-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/spanish\/"},{"@type":"ListItem","position":2,"name":"Glorificando A Dios En Todo &#8211; #1"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/spanish\/#website","url":"https:\/\/lifeword.org\/spanish\/","name":"Lifeword en Espa\u00f1ol","description":"Palabras De Vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/f479cc575d11904ff91d030f0bbb0518","name":"lifeword","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01041053782afe7c80a4df5ee8cb85e8f50e05fb8ebdc0dd9d654613395cd3e5?s=96&d=mm&r=g","caption":"lifeword"},"url":"https:\/\/lifeword.org\/spanish\/author\/lifeword\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg",1575,1575,false],"thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-150x150.jpg",150,150,true],"medium":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-300x300.jpg",300,300,true],"medium_large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-768x768.jpg",768,768,true],"large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-1024x1024.jpg",1024,1024,true],"1536x1536":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg",1536,1536,false],"2048x2048":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg",1575,1575,false],"post-thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-264x168.jpg",264,168,true],"lifeword-detail-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-775x437.jpg",775,437,true],"lifeword-slider-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-562x357.jpg",562,357,true],"lifeword-list-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo-600x480.jpg",600,480,true],"gform-image-choice-sm":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg",300,300,false],"gform-image-choice-md":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg",400,400,false],"gform-image-choice-lg":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2019\/04\/06_glorificando_a_Dios_en_todo.jpg",600,600,false]},"uagb_author_info":{"display_name":"lifeword","author_link":"https:\/\/lifeword.org\/spanish\/author\/lifeword\/"},"uagb_comment_info":0,"uagb_excerpt":"\u201cSi, pues, com\u00e9is o beb\u00e9is, o hac\u00e9is otra cosa, hacedlo todo para la gloria de Dios.\u201d \u202d\u202d1 Corintios\u202c \u202d10:31\u202c \u202dRVR1960\u202c\u202c [&hellip;]","_links":{"self":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/comments?post=360"}],"version-history":[{"count":1,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/360\/revisions"}],"predecessor-version":[{"id":362,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/360\/revisions\/362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media\/361"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media?parent=360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/categories?post=360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/tags?post=360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}