{"id":2386,"date":"2025-05-01T06:00:00","date_gmt":"2025-05-01T11:00:00","guid":{"rendered":"https:\/\/lifeword.org\/spanish\/?p=2386"},"modified":"2025-04-29T10:26:00","modified_gmt":"2025-04-29T15:26:00","slug":"el-dia-que-todo-cambio","status":"publish","type":"post","link":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/","title":{"rendered":"El D\u00eda que Todo Cambi\u00f3"},"content":{"rendered":"\n<p>Hace once a\u00f1os, el peso de un vac\u00edo insoportable me abrum\u00f3 hasta llevarme a un colapso emocional. Aunque en realidad fue un proceso lento, sent\u00ed como si mi mundo se viniera abajo de la noche a la ma\u00f1ana. Un d\u00eda ten\u00eda sue\u00f1os, entusiasmo, emoci\u00f3n y ambiciones que impulsaban mi carrera y mi vida personal; al siguiente, despert\u00e9 con una inquietud que me carcom\u00eda, exhausto f\u00edsica y emocionalmente.<\/p>\n\n\n\n<p>Intent\u00e9 salir adelante por mis propios medios. Ese d\u00eda tom\u00e9 el camino largo hacia el trabajo. El aire fr\u00edo entrando por las ventanas abiertas de mi peque\u00f1o Kia Rio rojo y el sol brillando entre las ramas secas de los \u00e1rboles deber\u00edan haberme revitalizado. Pero no fue as\u00ed. Mientras admiraba la majestuosidad de la creaci\u00f3n durante ese recorrido por caminos rurales, mi tristeza se profundizaba.<\/p>\n\n\n\n<p>\u201cNo importa\u201d, pens\u00e9. A\u00fan ten\u00eda mi trabajo, con tareas y responsabilidades que podr\u00edan distraerme. Quiz\u00e1 la rutina laboral podr\u00eda anestesiar ese vac\u00edo que me invad\u00eda. Pero mientras asist\u00eda a las reuniones de la ma\u00f1ana y revisaba incontables correos electr\u00f3nicos, me di cuenta de que cualquier rastro de motivaci\u00f3n me hab\u00eda abandonado. No ten\u00eda nada que dar. Ped\u00ed ayuda para cubrir y reprogramar mis citas y escrib\u00ed a mi equipo avis\u00e1ndoles que me ausentar\u00eda el resto del d\u00eda.<\/p>\n\n\n\n<p>En el camino de regreso, no tom\u00e9 las carreteras secundarias. En cambio, sub\u00ed el volumen de la radio y me incorpor\u00e9 a la autopista I-49 en direcci\u00f3n norte. Parec\u00eda que todas las estaciones de radio se hab\u00edan puesto de acuerdo para empeorar mi \u00e1nimo. Cambiaba de emisora: la de rock no ten\u00eda suficiente energ\u00eda, la de pop sonaba predecible y las noticias de NPR me resultaban indiferentes. Presion\u00e9 el bot\u00f3n de b\u00fasqueda autom\u00e1tica buscando algo nuevo. Termin\u00e9 escuchando m\u00fasica country mexicana por un rato, hasta que, casi sin querer, sintoniz\u00e9 a un predicador en la radio (algo que rara vez hac\u00eda en ese entonces). Era el programa Truth for Life de Alistair Begg.<br>Escuch\u00e9 mientras este predicador escoc\u00e9s explicaba la Biblia de manera tan clara y profunda que algo se movi\u00f3 dentro de m\u00ed. \u00a1Necesitaba verlo con mis propios ojos!<\/p>\n\n\n\n<p>Al llegar a casa, saqu\u00e9 de la repisa una Biblia de estudio de aplicaci\u00f3n personal (NVI), de cuero marr\u00f3n bicolor, que mi t\u00edo me hab\u00eda regalado cuando ten\u00eda 14 a\u00f1os. Ten\u00eda tanto polvo que tuve que limpiarla con una toalla h\u00fameda.<\/p>\n\n\n\n<p>Me sent\u00e9 en el solario y le\u00ed hasta que cay\u00f3 la noche. \u00a1No pod\u00eda creer lo mucho que me atrap\u00f3 la Palabra de Dios! Yo hab\u00eda renunciado a la \u201ccristiandad\u201d a\u00f1os antes, en mi tercer a\u00f1o de secundaria. Hab\u00eda le\u00eddo la Biblia solo para debatir y aparentar sabidur\u00eda. Pero ese d\u00eda, cuando mi coraz\u00f3n se rebel\u00f3 sin raz\u00f3n aparente, la Biblia cobr\u00f3 vida para m\u00ed.<\/p>\n\n\n\n<p>Avanzando en mi historia, eventualmente regres\u00e9 a la peque\u00f1a iglesia bautista a la que me hab\u00eda unido cuando estaba en secundaria. Por curiosidad, me preguntaba si, al igual que con la Biblia, me hab\u00eda perdido de algo en mi inmadurez juvenil. \u00bfPuedes creer que encontr\u00e9 exactamente eso? Aprend\u00ed a mantener un descubrimiento guiado por el Esp\u00edritu a trav\u00e9s de la Palabra de Dios. Descubr\u00ed lo que realmente me hab\u00eda estado faltando: no solo conocimiento, sino una vida transformada por el poder de Su Palabra.<\/p>\n\n\n\n<p>Por eso es tan importante el estudio b\u00edblico. No es simplemente un ejercicio acad\u00e9mico; es la manera en que Dios nos habla. Oro para que t\u00fa tambi\u00e9n descubras esa misma alegr\u00eda, profundidad y renovaci\u00f3n a trav\u00e9s de la Palabra de Dios. Todo empieza con una pregunta sencilla: \u00bfQu\u00e9 dice la Biblia? \ud83d\udcd6<\/p>\n\n\n\n<p><strong><em>Copyright \u00a9 2025 by Derrick Bremer @ <\/em><\/strong><a href=\"http:\/\/livingoutthegospel.com\"><strong><em>LivingOutTheGospel.com<\/em><\/strong><\/a> <strong><em>&nbsp;No part of this article may be reproduced or reprinted without permission in writing from <\/em><\/strong><a href=\"http:\/\/lifeword.org\/\"><strong><em>Lifeword.org<\/em><\/strong><\/a><strong><em>.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Biblia cobr\u00f3 vida para m\u00ed.<\/p>\n","protected":false},"author":97,"featured_media":2387,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[1640,1630,1635,1632,1639,1631],"tags":[251,2799,3310,31,1758,3205,1275],"class_list":["post-2386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crecimiento-espiritual","category-devocionales","category-evangelismo","category-la-iglesia","category-problemas-de-la-vida","category-vida-cristiana","tag-dolor","tag-emociones","tag-exhausto","tag-jesus","tag-motivacion","tag-respuestas","tag-suenos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El D\u00eda que Todo Cambi\u00f3 - Lifeword en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El D\u00eda que Todo Cambi\u00f3 - Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"La Biblia cobr\u00f3 vida para m\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-01T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"562\" \/>\n\t<meta property=\"og:image:height\" content=\"357\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernanda Posadas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernanda Posadas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/el-dia-que-todo-cambio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/el-dia-que-todo-cambio\\\/\"},\"author\":{\"name\":\"Fernanda Posadas\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\"},\"headline\":\"El D\u00eda que Todo Cambi\u00f3\",\"datePublished\":\"2025-05-01T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/el-dia-que-todo-cambio\\\/\"},\"wordCount\":689,\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/el-dia-que-todo-cambio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/05\\\/Image-1.jpeg\",\"keywords\":[\"dolor\",\"Emociones\",\"exhausto\",\"Jes\u00fas\",\"Motivacion\",\"respuestas\",\"sue\u00f1os\"],\"articleSection\":[\"Crecimiento Espiritual\",\"Devocionales\",\"Evangelismo\",\"La Iglesia\",\"Problemas De La Vida\",\"Vida Cristiana\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/el-dia-que-todo-cambio\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/el-dia-que-todo-cambio\\\/\",\"name\":\"El D\u00eda que Todo Cambi\u00f3 - Lifeword en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/el-dia-que-todo-cambio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/el-dia-que-todo-cambio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/05\\\/Image-1.jpeg\",\"datePublished\":\"2025-05-01T11:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/el-dia-que-todo-cambio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/el-dia-que-todo-cambio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/el-dia-que-todo-cambio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/05\\\/Image-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/05\\\/Image-1.jpeg\",\"width\":562,\"height\":357},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/el-dia-que-todo-cambio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El D\u00eda que Todo Cambi\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\",\"name\":\"Lifeword en Espa\u00f1ol\",\"description\":\"Palabras De Vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\",\"name\":\"Fernanda Posadas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"caption\":\"Fernanda Posadas\"},\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/author\\\/fernanda-posadas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El D\u00eda que Todo Cambi\u00f3 - Lifeword en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/","og_locale":"es_ES","og_type":"article","og_title":"El D\u00eda que Todo Cambi\u00f3 - Lifeword en Espa\u00f1ol","og_description":"La Biblia cobr\u00f3 vida para m\u00ed.","og_url":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/","og_site_name":"Lifeword en Espa\u00f1ol","article_published_time":"2025-05-01T11:00:00+00:00","og_image":[{"width":562,"height":357,"url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg","type":"image\/jpeg"}],"author":"Fernanda Posadas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fernanda Posadas","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/#article","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/"},"author":{"name":"Fernanda Posadas","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18"},"headline":"El D\u00eda que Todo Cambi\u00f3","datePublished":"2025-05-01T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/"},"wordCount":689,"image":{"@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg","keywords":["dolor","Emociones","exhausto","Jes\u00fas","Motivacion","respuestas","sue\u00f1os"],"articleSection":["Crecimiento Espiritual","Devocionales","Evangelismo","La Iglesia","Problemas De La Vida","Vida Cristiana"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/","url":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/","name":"El D\u00eda que Todo Cambi\u00f3 - Lifeword en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/#primaryimage"},"image":{"@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg","datePublished":"2025-05-01T11:00:00+00:00","author":{"@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/#primaryimage","url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg","contentUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg","width":562,"height":357},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/el-dia-que-todo-cambio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/spanish\/"},{"@type":"ListItem","position":2,"name":"El D\u00eda que Todo Cambi\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/spanish\/#website","url":"https:\/\/lifeword.org\/spanish\/","name":"Lifeword en Espa\u00f1ol","description":"Palabras De Vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18","name":"Fernanda Posadas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","caption":"Fernanda Posadas"},"url":"https:\/\/lifeword.org\/spanish\/author\/fernanda-posadas\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg",562,357,false],"thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1-150x150.jpeg",150,150,true],"medium":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1-300x191.jpeg",300,191,true],"medium_large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg",562,357,false],"large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg",562,357,false],"1536x1536":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg",562,357,false],"2048x2048":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg",562,357,false],"post-thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1-264x168.jpeg",264,168,true],"lifeword-detail-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg",562,357,false],"lifeword-slider-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg",562,357,false],"lifeword-list-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg",562,357,false],"gform-image-choice-sm":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg",300,191,false],"gform-image-choice-md":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg",400,254,false],"gform-image-choice-lg":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2025\/05\/Image-1.jpeg",562,357,false]},"uagb_author_info":{"display_name":"Fernanda Posadas","author_link":"https:\/\/lifeword.org\/spanish\/author\/fernanda-posadas\/"},"uagb_comment_info":0,"uagb_excerpt":"La Biblia cobr\u00f3 vida para m\u00ed.","_links":{"self":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/comments?post=2386"}],"version-history":[{"count":1,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2386\/revisions"}],"predecessor-version":[{"id":2388,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2386\/revisions\/2388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media\/2387"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media?parent=2386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/categories?post=2386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/tags?post=2386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}