{"id":2299,"date":"2024-11-01T06:00:00","date_gmt":"2024-11-01T11:00:00","guid":{"rendered":"https:\/\/lifeword.org\/spanish\/?p=2299"},"modified":"2024-10-30T16:03:32","modified_gmt":"2024-10-30T21:03:32","slug":"la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate","status":"publish","type":"post","link":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/","title":{"rendered":"La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate"},"content":{"rendered":"\n<p>La medida del significado<\/p>\n\n\n\n<p>\u00bfC\u00f3mo se mide la importancia? \u00bfC\u00f3mo calculas el valor verdadero que una persona o cosa tiene en tu vida? (Por cierto, el mundo no mide correctamente el significado. Solo la Biblia lo hace bien.)<\/p>\n\n\n\n<p>Es sencillo.<\/p>\n\n\n\n<p>El verdadero significado se mide por c\u00f3mo reaccionas cuando esa persona o cosa se pierde.<\/p>\n\n\n\n<p>Pi\u00e9nsalo. Cuando pierdes un calcet\u00edn, probablemente el esfuerzo de b\u00fasqueda es m\u00ednimo. Quiz\u00e1s buscas en el caj\u00f3n, revisas la canasta de ropa sucia y hasta miras en la secadora. Pero eso es todo. Un calcet\u00edn no tiene suficiente valor o significado como para iniciar una misi\u00f3n de b\u00fasqueda y rescate exhaustiva.<\/p>\n\n\n\n<p><em>B\u00fasqueda peque\u00f1a = poco significado.<\/em><\/p>\n\n\n\n<p>Sin embargo, \u00bfqu\u00e9 tal si pierdes tu anillo de bodas? Imagino que la b\u00fasqueda de un anillo de bodas valioso superar\u00eda con creces la b\u00fasqueda de un calcet\u00edn. Un anillo de bodas tiene un valor sentimental y monetario. Por lo tanto, su valor aumenta el esfuerzo de b\u00fasqueda y revela su importancia. En tu b\u00fasqueda, pedir\u00edas ayuda a otros, y la b\u00fasqueda no terminar\u00eda hasta que lo encontraras.<\/p>\n\n\n\n<p><em>B\u00fasqueda grande = gran significado.<\/em><\/p>\n\n\n\n<p>Aqu\u00ed est\u00e1 el punto. El verdadero significado se puede medir por el alcance de la b\u00fasqueda.<\/p>\n\n\n\n<p>Esta afirmaci\u00f3n es cierta si has perdido el control remoto, un zapato, tu cartera, una mascota, tu trabajo o una reliquia familiar. Cuanto mayor es el valor de algo, mayor esfuerzo pondr\u00e1s para encontrarlo cuando se pierde.<\/p>\n\n\n\n<p>\u00bfSab\u00edas que la misi\u00f3n de Jes\u00fas revela algo sobre nuestra importancia para Dios?<\/p>\n\n\n\n<p>La misi\u00f3n de Jes\u00fas<\/p>\n\n\n\n<p>Jes\u00fas no estaba en una misi\u00f3n secreta. Nos dice claramente qu\u00e9 est\u00e1 haciendo aqu\u00ed en la tierra:<\/p>\n\n\n\n<p>\u201cPorque el Hijo del Hombre vino a buscar y a salvar lo que se hab\u00eda perdido.\u201d Lucas 19:10<\/p>\n\n\n\n<p>La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate total. Jes\u00fas vino a buscar y salvar; a encontrar y rescatar.<\/p>\n\n\n\n<p>Lucas 15 es uno de mis cap\u00edtulos favoritos en toda la Escritura porque ilustra perfectamente (\u00a1tres veces!) la belleza de la b\u00fasqueda incansable de Dios.<\/p>\n\n\n\n<p>La par\u00e1bola de la oveja perdida en Lucas 15:1-7 muestra c\u00f3mo Jes\u00fas dejar\u00eda a las noventa y nueve para ir tras la que se perdi\u00f3.<\/p>\n\n\n\n<p>La par\u00e1bola de la moneda perdida en Lucas 15:8-10 muestra c\u00f3mo Jes\u00fas persiste hasta encontrar lo que est\u00e1 perdido.<\/p>\n\n\n\n<p>La par\u00e1bola del hijo pr\u00f3digo en Lucas 15:11-32 nos recuerda que, sin importar cu\u00e1nto nos hayamos alejado, el Padre nos espera con los brazos abiertos para que regresemos a casa.<\/p>\n\n\n\n<p>En cada b\u00fasqueda, el objeto perdido es hallado. En cada b\u00fasqueda, se celebra con alegr\u00eda.<\/p>\n\n\n\n<p>La medida del significado<\/p>\n\n\n\n<p>Si el verdadero significado se mide por el alcance de la b\u00fasqueda, entonces puedes estar seguro de esto hoy: la b\u00fasqueda de Dios por nosotros revela nuestra importancia para \u00c9l.<\/p>\n\n\n\n<p>Eres importante para Dios. Eres muy valorado y amado profundamente. \u00a1De verdad!<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fuiste creado a Su imagen. (G\u00e9nesis 1:27)<\/li>\n\n\n\n<li>Eres dise\u00f1ado de forma \u00fanica. (Salmos 139:14)<\/li>\n\n\n\n<li>Te ha dado un prop\u00f3sito sobrenatural. (Jerem\u00edas 29:11)<\/li>\n\n\n\n<li>Est\u00e1s divinamente empoderado. (Hechos 1:8)<\/li>\n\n\n\n<li>Eres abundantemente bendecido. (Efesios 1:3)<\/li>\n\n\n\n<li>Dios se preocupa tanto por ti que, aun cuando eras pecador, Jes\u00fas muri\u00f3 por ti. (Romanos 5:8)<\/li>\n<\/ul>\n\n\n\n<p>Jes\u00fas no busca a las personas que tienen sus vidas perfectamente en orden. No persigue a quien es bueno. Persigue a quien est\u00e1 perdido. \u00bfPor qu\u00e9 har\u00eda eso? \u00a1Porque eres importante para Dios!<\/p>\n\n\n\n<p>Vive hoy sabiendo lo valioso que eres para Dios.<\/p>\n\n\n\n<p><em>Copyright \u00a9 2021 by Andy Comer @ https:\/\/antiochgt.com\/blog\/what-jesus-mission-reveals-about-your-significance\/. No part of this article may be reproduced or reprinted without permission in writing from\u00a0<\/em><a href=\"http:\/\/lifeword.org\/\"><em>Lifeword.org<\/em><\/a><em>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLa misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate total.\u00bb<\/p>\n","protected":false},"author":97,"featured_media":2300,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[2359,1640,1635,1631],"tags":[42,3189,31,593,1672,1522],"class_list":["post-2299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-crecimiento-espiritual","category-evangelismo","category-vida-cristiana","tag-amor","tag-busqueda","tag-jesus","tag-ovejas","tag-parabola","tag-pecadores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate - Lifeword en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate - Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"&quot;La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate total.&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-01T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Fernanda Posadas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernanda Posadas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/evangelismo\\\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/evangelismo\\\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\\\/\"},\"author\":{\"name\":\"Fernanda Posadas\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\"},\"headline\":\"La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate\",\"datePublished\":\"2024-11-01T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/evangelismo\\\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\\\/\"},\"wordCount\":658,\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/evangelismo\\\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/email-campaign-images-6.png\",\"keywords\":[\"amor\",\"busqueda\",\"Jes\u00fas\",\"ovejas\",\"par\u00e1bola\",\"pecadores\"],\"articleSection\":[\"Blog\",\"Crecimiento Espiritual\",\"Evangelismo\",\"Vida Cristiana\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/evangelismo\\\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/evangelismo\\\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\\\/\",\"name\":\"La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate - Lifeword en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/evangelismo\\\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/evangelismo\\\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/email-campaign-images-6.png\",\"datePublished\":\"2024-11-01T11:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/evangelismo\\\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/evangelismo\\\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/evangelismo\\\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/email-campaign-images-6.png\",\"contentUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/email-campaign-images-6.png\",\"width\":6000,\"height\":3375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/evangelismo\\\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\",\"name\":\"Lifeword en Espa\u00f1ol\",\"description\":\"Palabras De Vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\",\"name\":\"Fernanda Posadas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"caption\":\"Fernanda Posadas\"},\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/author\\\/fernanda-posadas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate - Lifeword en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/","og_locale":"es_ES","og_type":"article","og_title":"La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate - Lifeword en Espa\u00f1ol","og_description":"\"La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate total.\"","og_url":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/","og_site_name":"Lifeword en Espa\u00f1ol","article_published_time":"2024-11-01T11:00:00+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6-1024x576.png","type":"image\/png"}],"author":"Fernanda Posadas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fernanda Posadas","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/#article","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/"},"author":{"name":"Fernanda Posadas","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18"},"headline":"La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate","datePublished":"2024-11-01T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/"},"wordCount":658,"image":{"@id":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6.png","keywords":["amor","busqueda","Jes\u00fas","ovejas","par\u00e1bola","pecadores"],"articleSection":["Blog","Crecimiento Espiritual","Evangelismo","Vida Cristiana"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/","url":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/","name":"La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate - Lifeword en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/#primaryimage"},"image":{"@id":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6.png","datePublished":"2024-11-01T11:00:00+00:00","author":{"@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/#primaryimage","url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6.png","contentUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6.png","width":6000,"height":3375},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/spanish\/evangelismo\/la-mision-de-jesus-es-una-mision-de-busqueda-y-rescate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/spanish\/"},{"@type":"ListItem","position":2,"name":"La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/spanish\/#website","url":"https:\/\/lifeword.org\/spanish\/","name":"Lifeword en Espa\u00f1ol","description":"Palabras De Vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18","name":"Fernanda Posadas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","caption":"Fernanda Posadas"},"url":"https:\/\/lifeword.org\/spanish\/author\/fernanda-posadas\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6.png",6000,3375,false],"thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6-150x150.png",150,150,true],"medium":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6-300x169.png",300,169,true],"medium_large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6-768x432.png",768,432,true],"large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6-1024x576.png",1024,576,true],"1536x1536":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6-1536x864.png",1536,864,true],"2048x2048":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6-2048x1152.png",2048,1152,true],"post-thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6-264x168.png",264,168,true],"lifeword-detail-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6-775x437.png",775,437,true],"lifeword-slider-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6-562x357.png",562,357,true],"lifeword-list-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6-600x480.png",600,480,true],"gform-image-choice-sm":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6.png",300,169,false],"gform-image-choice-md":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6.png",400,225,false],"gform-image-choice-lg":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/11\/email-campaign-images-6.png",600,338,false]},"uagb_author_info":{"display_name":"Fernanda Posadas","author_link":"https:\/\/lifeword.org\/spanish\/author\/fernanda-posadas\/"},"uagb_comment_info":0,"uagb_excerpt":"\"La misi\u00f3n de Jes\u00fas es una misi\u00f3n de b\u00fasqueda y rescate total.\"","_links":{"self":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/comments?post=2299"}],"version-history":[{"count":2,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2299\/revisions"}],"predecessor-version":[{"id":2302,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2299\/revisions\/2302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media\/2300"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media?parent=2299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/categories?post=2299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/tags?post=2299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}