{"id":2254,"date":"2024-10-08T08:00:00","date_gmt":"2024-10-08T13:00:00","guid":{"rendered":"https:\/\/lifeword.org\/spanish\/?p=2254"},"modified":"2024-10-07T14:17:11","modified_gmt":"2024-10-07T19:17:11","slug":"ven-y-ve","status":"publish","type":"post","link":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/","title":{"rendered":"Ven y ve"},"content":{"rendered":"\n<p><em>\u00abVenid y ved&#8230;\u00bb<\/em><\/p>\n\n\n\n<p>Puedo escuchar la melod\u00eda en mi mente al recordar c\u00f3mo se abrieron esas puertas, y un mundo maravilloso de dulces y delicias apareci\u00f3 ante mis ojos en la pantalla.<\/p>\n\n\n\n<p><em>Willy Wonka y la F\u00e1brica de Chocolate<\/em> fue una historia llena de sue\u00f1os e \u201cimaginaci\u00f3n pura\u201d. Wonka era el due\u00f1o de una incre\u00edble f\u00e1brica a la que nadie hab\u00eda visto por dentro. De repente, la noticia de que Wonka abrir\u00eda las puertas al p\u00fablico comenz\u00f3 a esparcirse como fuego. Ten\u00edas que conseguir uno de los cinco boletos dorados para entrar. Y estos boletos estaban escondidos dentro de las deliciosas barras de chocolate Wonka. \u00bfC\u00f3mo hac\u00eda Wonka este incre\u00edble chocolate y dulces? \u00bfCu\u00e1l era su secreto?<\/p>\n\n\n\n<p>Los poseedores de los boletos, todos eran ni\u00f1os, fueron abordados en secreto para robar la f\u00f3rmula de los dulces de Wonka. \u00bfRevelar\u00edan lo que aprendieron de esa oportunidad \u00fanica en la vida?<\/p>\n\n\n\n<p>Uno por uno, los ni\u00f1os fueron tentados y fallaron. Al final del d\u00eda, solo qued\u00f3 un peque\u00f1o, Charlie. Con una familia extremadamente pobre, Charlie tambi\u00e9n se sinti\u00f3 tentado. Podr\u00eda llevar el caramelo \u201cgobstopper eterno\u201d al hombre misterioso y venderlo para ayudar a su familia.<\/p>\n\n\n\n<p>Wonka lo puso a prueba y, al final, Charlie eligi\u00f3 hacer lo correcto. En un acto de arrepentimiento, dej\u00f3 el caramelo y se fue.<\/p>\n\n\n\n<p>En realidad, Willy Wonka hab\u00eda estado buscando un sucesor. Alguien que tuviera un coraz\u00f3n puro. Alguien que fuera confiable, honesto y que estuviera all\u00ed por las razones correctas. Wonka ten\u00eda un tesoro y quer\u00eda estar seguro antes de entregarlo.<\/p>\n\n\n\n<p>Wonka celebra con Charlie y su abuelo cuando se da cuenta de que este joven tom\u00f3 la decisi\u00f3n correcta.<\/p>\n\n\n\n<p><strong>Juan 1:35-39<\/strong><\/p>\n\n\n\n<p><sup>35<\/sup> \u00abEl siguiente d\u00eda otra vez estaba Juan, y dos de sus disc\u00edpulos.<\/p>\n\n\n\n<p><sup>36<\/sup> Y mirando a Jes\u00fas que andaba por all\u00ed, dijo: He aqu\u00ed el Cordero de Dios.<\/p>\n\n\n\n<p><sup>37<\/sup> Le oyeron hablar los dos disc\u00edpulos, y siguieron a Jes\u00fas.<\/p>\n\n\n\n<p><sup>38<\/sup> Y volvi\u00e9ndose Jes\u00fas, y viendo que le segu\u00edan, les dijo: \u00bfQu\u00e9 busc\u00e1is? Ellos le dijeron: Rab\u00ed (que traducido es, Maestro), \u00bfd\u00f3nde moras?<\/p>\n\n\n\n<p><sup>39<\/sup> Les dijo: Venid y ved. Fueron, y vieron d\u00f3nde moraba, y se quedaron con \u00e9l aquel d\u00eda; porque era como la hora d\u00e9cima.\u00bb<\/p>\n\n\n\n<p>Juan el Bautista hab\u00eda estado predicando durante a\u00f1os acerca de la venida del Mes\u00edas. Algunos hombres lo segu\u00edan, aprendiendo acerca de Dios, Sus caminos, Sus mandamientos, y del Salvador que estaba por venir. Pero en este d\u00eda, ellos conocer\u00edan a ese Salvador.<\/p>\n\n\n\n<p>Eran disc\u00edpulos de Juan para aprender acerca de Jes\u00fas, pero ahora ser\u00edan disc\u00edpulos de Jes\u00fas mismo. Pero primero, deb\u00edan responder una pregunta. Jes\u00fas los puso a prueba.<\/p>\n\n\n\n<p>Les pregunt\u00f3: \u201c\u00bfQu\u00e9 busc\u00e1is?\u201d \u00bfQu\u00e9 estaban buscando? \u00bfPor qu\u00e9 eleg\u00edan seguir a Jes\u00fas? \u00bfQuer\u00edan fama y fortuna para hacerse un nombre? No pod\u00eda ser por deseos ego\u00edstas. Jes\u00fas estaba buscando hombres que lo siguieran por las razones correctas.<\/p>\n\n\n\n<p>Les dijo: \u201cVenid y ved\u201d.<\/p>\n\n\n\n<p>Estos hombres decidir\u00edan seguir a Cristo. Pero no sabr\u00edan lo que eso realmente significar\u00eda hasta tres a\u00f1os despu\u00e9s. La persecuci\u00f3n vendr\u00eda, no la fama ni la fortuna. \u00bfSeguir\u00edan eligiendo seguirlo entonces?<\/p>\n\n\n\n<p>Jes\u00fas nos hace la misma pregunta hoy. Nos toca el coraz\u00f3n para que escuchemos, oigamos Sus palabras y entendamos la depravaci\u00f3n de nuestro pecado y la separaci\u00f3n que causa entre nosotros y Dios. \u00c9l extiende Sus brazos de bienvenida mientras sentimos la culpa y la verg\u00fcenza de esos pecados y los confesamos, buscando el perd\u00f3n. Y surge la pregunta&#8230; \u00bfpor qu\u00e9? \u00bfPor qu\u00e9 elegir\u00eda seguir a Jes\u00fas? \u00bfPor qu\u00e9 entregar\u00eda mi vida y mi voluntad a \u00c9l? \u00bfQu\u00e9 es lo que creo acerca de \u00c9l que me har\u00eda querer hacer eso? \u00bfLo estoy haciendo por un beneficio personal, o realmente quiero conocer a Cristo y darlo a conocer?<\/p>\n\n\n\n<p><em>\u201c\u00bfQu\u00e9 busc\u00e1is?\u201d<\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfPor qu\u00e9 sigues a Jes\u00fas?<\/p>\n","protected":false},"author":97,"featured_media":2255,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[1640,1630,1631],"tags":[31,36,484,497,2722],"class_list":["post-2254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crecimiento-espiritual","category-devocionales","category-vida-cristiana","tag-jesus","tag-pecado","tag-sacrificio","tag-seguirle","tag-su-voluntad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ven y ve - Lifeword en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ven y ve - Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"\u00bfPor qu\u00e9 sigues a Jes\u00fas?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-08T13:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"562\" \/>\n\t<meta property=\"og:image:height\" content=\"357\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernanda Posadas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernanda Posadas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ven-y-ve\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ven-y-ve\\\/\"},\"author\":{\"name\":\"Fernanda Posadas\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\"},\"headline\":\"Ven y ve\",\"datePublished\":\"2024-10-08T13:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ven-y-ve\\\/\"},\"wordCount\":696,\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ven-y-ve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/Image-2.jpeg\",\"keywords\":[\"Jes\u00fas\",\"pecado\",\"sacrificio\",\"seguirle\",\"Su voluntad\"],\"articleSection\":[\"Crecimiento Espiritual\",\"Devocionales\",\"Vida Cristiana\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ven-y-ve\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ven-y-ve\\\/\",\"name\":\"Ven y ve - Lifeword en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ven-y-ve\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ven-y-ve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/Image-2.jpeg\",\"datePublished\":\"2024-10-08T13:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ven-y-ve\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ven-y-ve\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ven-y-ve\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/Image-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/10\\\/Image-2.jpeg\",\"width\":562,\"height\":357},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ven-y-ve\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ven y ve\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\",\"name\":\"Lifeword en Espa\u00f1ol\",\"description\":\"Palabras De Vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\",\"name\":\"Fernanda Posadas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"caption\":\"Fernanda Posadas\"},\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/author\\\/fernanda-posadas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ven y ve - Lifeword en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/","og_locale":"es_ES","og_type":"article","og_title":"Ven y ve - Lifeword en Espa\u00f1ol","og_description":"\u00bfPor qu\u00e9 sigues a Jes\u00fas?","og_url":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/","og_site_name":"Lifeword en Espa\u00f1ol","article_published_time":"2024-10-08T13:00:00+00:00","og_image":[{"width":562,"height":357,"url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg","type":"image\/jpeg"}],"author":"Fernanda Posadas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fernanda Posadas","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/#article","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/"},"author":{"name":"Fernanda Posadas","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18"},"headline":"Ven y ve","datePublished":"2024-10-08T13:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/"},"wordCount":696,"image":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg","keywords":["Jes\u00fas","pecado","sacrificio","seguirle","Su voluntad"],"articleSection":["Crecimiento Espiritual","Devocionales","Vida Cristiana"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/","url":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/","name":"Ven y ve - Lifeword en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/#primaryimage"},"image":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg","datePublished":"2024-10-08T13:00:00+00:00","author":{"@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/#primaryimage","url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg","contentUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg","width":562,"height":357},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ven-y-ve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/spanish\/"},{"@type":"ListItem","position":2,"name":"Ven y ve"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/spanish\/#website","url":"https:\/\/lifeword.org\/spanish\/","name":"Lifeword en Espa\u00f1ol","description":"Palabras De Vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18","name":"Fernanda Posadas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","caption":"Fernanda Posadas"},"url":"https:\/\/lifeword.org\/spanish\/author\/fernanda-posadas\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg",562,357,false],"thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2-150x150.jpeg",150,150,true],"medium":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2-300x191.jpeg",300,191,true],"medium_large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg",562,357,false],"large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg",562,357,false],"1536x1536":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg",562,357,false],"2048x2048":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg",562,357,false],"post-thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2-264x168.jpeg",264,168,true],"lifeword-detail-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg",562,357,false],"lifeword-slider-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg",562,357,false],"lifeword-list-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg",562,357,false],"gform-image-choice-sm":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg",300,191,false],"gform-image-choice-md":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg",400,254,false],"gform-image-choice-lg":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/10\/Image-2.jpeg",562,357,false]},"uagb_author_info":{"display_name":"Fernanda Posadas","author_link":"https:\/\/lifeword.org\/spanish\/author\/fernanda-posadas\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00bfPor qu\u00e9 sigues a Jes\u00fas?","_links":{"self":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/comments?post=2254"}],"version-history":[{"count":1,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2254\/revisions"}],"predecessor-version":[{"id":2256,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2254\/revisions\/2256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media\/2255"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media?parent=2254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/categories?post=2254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/tags?post=2254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}