{"id":2089,"date":"2024-04-16T08:00:00","date_gmt":"2024-04-16T13:00:00","guid":{"rendered":"https:\/\/lifeword.org\/spanish\/?p=2089"},"modified":"2024-04-15T17:19:09","modified_gmt":"2024-04-15T22:19:09","slug":"dios-termina-ganando","status":"publish","type":"post","link":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/","title":{"rendered":"Dios termina ganando"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hemos estado viendo una serie llamada &#8216;Leverage&#8217;. Este grupo es como una especie de Robin Hood contempor\u00e1neo. Ayudan a personas que han sido perjudicadas por ricos poderosos, astutos y malintencionados que de otro modo ser\u00edan intocables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ciertos momentos, parece que el villano tiene el control y saldr\u00e1 victorioso al final. Pero, de repente, se revela la verdad, el enemigo es derrotado y se muestra que el grupo realmente ten\u00eda el control todo el tiempo. Todo era parte de su plan. Y el enemigo queda boquiabierto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lucas 22:66-71<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>66<\/sup>\u00a0Al amanecer, todos los ancianos del pueblo se reunieron, incluidos los principales sacerdotes y los maestros de la ley religiosa. Llevaron a Jes\u00fas ante el Concilio Supremo\u00a0<sup>67<\/sup>\u00a0y le dijeron:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014Dinos, \u00bferes t\u00fa el Mes\u00edas?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9l les respondi\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014Si lo dijera, no me creer\u00edan;\u00a0<sup>68<\/sup>\u00a0y si yo les hiciera una pregunta, ustedes no me la contestar\u00edan.\u00a0<sup>69<\/sup>\u00a0Sin embargo, desde ahora, el Hijo del Hombre estar\u00e1 sentado en el lugar de poder, a la derecha de Dios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>70<\/sup>\u00a0Todos gritaron:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014\u00bfEntonces afirmas que eres el Hijo de Dios?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y \u00e9l contest\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014Ustedes dicen que lo soy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>71\u00a0<\/sup>\u00ab\u00bfPara qu\u00e9 necesitamos otros testigos?\u2014dijeron\u2014. Nosotros mismos lo o\u00edmos decirlo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parece que el enemigo tiene la ventaja. Lo han arrestado y no se detendr\u00e1n ante nada para conseguir lo que quieren. Los l\u00edderes religiosos estaban haciendo todo lo posible por hacer que Jes\u00fas dijera que era el Hijo de Dios, lo cual seg\u00fan su ley ser\u00eda blasfemo. Para cualquiera otro, lo ser\u00eda. Pero para Jes\u00fas, era simplemente la verdad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero Jes\u00fas agrega esta declaraci\u00f3n que me absolutamente me encanta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi lo dijera, no me creer\u00edan;&nbsp;y si yo les hiciera una pregunta, ustedes no me la contestar\u00edan.&nbsp;Sin embargo, desde ahora, el Hijo del Hombre estar\u00e1 sentado en el lugar de poder, a la derecha de Dios\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jes\u00fas sabe lo que est\u00e1 sucediendo y lo que depara el futuro. Pero, los hombres astutos est\u00e1n desprevenidos. Piensan que tienen el control y conseguir\u00e1n lo que han venido a buscar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cUstedes dicen que lo soy\u201d fue suficiente para que lo acusaran de blasfemia. Un cargo que significaba una muerte segura. Ten\u00edan lo que necesitaban.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, \u00bfsabemos c\u00f3mo termina, verdad?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque parece que la esperanza est\u00e1 perdida y el enemigo tiene el control, sabemos que Dios tiene un plan maestro. No solo para derrotar a estos l\u00edderes religiosos, sino para vencer al mal, la muerte y Satan\u00e1s. Pronto, la verdad ser\u00e1 revelada cuando Jes\u00fas resucite de entre los muertos. Y el enemigo quedar\u00e1 boquiabierto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfTe sientes as\u00ed hoy? Tal vez est\u00e9s lidiando con algo y sientes que el enemigo tiene el control. Tu voz no est\u00e1 siendo escuchada o incluso si hablas, nadie te escucha. Sientes que te est\u00e1n acorralando y solo quieres que se revele la verdad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo ser\u00e1. En su debido tiempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como Jes\u00fas sol\u00eda hacer, t\u00f3mate tiempo para alejarte y orar. Busca la sabidur\u00eda del Se\u00f1or y pide discernimiento en esta situaci\u00f3n. Estudia su Palabra y v\u00edvela. Sabes qui\u00e9n gana al final. Conf\u00eda en Dios para resolverlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Copyright \u00a9 2023 by Yalanda Merrell\u00a0<\/em><\/strong><a href=\"http:\/\/lifeword.org\/\"><strong><em>Lifeword.org<\/em><\/strong><\/a><strong><em>. All rights reserved. No part of this article may be reproduced or reprinted without permission in writing from\u00a0<\/em><\/strong><a href=\"http:\/\/lifeword.org\/\"><strong><em>Lifeword.org<\/em><\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Dios ya venci\u00f3! Entr\u00e9gale tus batallas.<\/p>\n","protected":false},"author":97,"featured_media":2090,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[1640,1630,1639],"tags":[1299,407,31,484,1062],"class_list":["post-2089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crecimiento-espiritual","category-devocionales","category-problemas-de-la-vida","tag-batallas","tag-enemigos","tag-jesus","tag-sacrificio","tag-victoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dios termina ganando - Lifeword en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dios termina ganando - Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"\u00a1Dios ya venci\u00f3! Entr\u00e9gale tus batallas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T13:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"562\" \/>\n\t<meta property=\"og:image:height\" content=\"357\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernanda Posadas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernanda Posadas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/dios-termina-ganando\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/dios-termina-ganando\\\/\"},\"author\":{\"name\":\"Fernanda Posadas\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\"},\"headline\":\"Dios termina ganando\",\"datePublished\":\"2024-04-16T13:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/dios-termina-ganando\\\/\"},\"wordCount\":569,\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/dios-termina-ganando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/04\\\/Image-1.jpeg\",\"keywords\":[\"batallas\",\"enemigos\",\"Jes\u00fas\",\"sacrificio\",\"victoria\"],\"articleSection\":[\"Crecimiento Espiritual\",\"Devocionales\",\"Problemas De La Vida\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/dios-termina-ganando\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/dios-termina-ganando\\\/\",\"name\":\"Dios termina ganando - Lifeword en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/dios-termina-ganando\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/dios-termina-ganando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/04\\\/Image-1.jpeg\",\"datePublished\":\"2024-04-16T13:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/dios-termina-ganando\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/dios-termina-ganando\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/dios-termina-ganando\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/04\\\/Image-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/04\\\/Image-1.jpeg\",\"width\":562,\"height\":357},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/problemas-de-la-vida\\\/dios-termina-ganando\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dios termina ganando\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\",\"name\":\"Lifeword en Espa\u00f1ol\",\"description\":\"Palabras De Vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\",\"name\":\"Fernanda Posadas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"caption\":\"Fernanda Posadas\"},\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/author\\\/fernanda-posadas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dios termina ganando - Lifeword en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/","og_locale":"es_ES","og_type":"article","og_title":"Dios termina ganando - Lifeword en Espa\u00f1ol","og_description":"\u00a1Dios ya venci\u00f3! Entr\u00e9gale tus batallas.","og_url":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/","og_site_name":"Lifeword en Espa\u00f1ol","article_published_time":"2024-04-16T13:00:00+00:00","og_image":[{"width":562,"height":357,"url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg","type":"image\/jpeg"}],"author":"Fernanda Posadas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fernanda Posadas","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/#article","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/"},"author":{"name":"Fernanda Posadas","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18"},"headline":"Dios termina ganando","datePublished":"2024-04-16T13:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/"},"wordCount":569,"image":{"@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg","keywords":["batallas","enemigos","Jes\u00fas","sacrificio","victoria"],"articleSection":["Crecimiento Espiritual","Devocionales","Problemas De La Vida"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/","url":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/","name":"Dios termina ganando - Lifeword en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/#primaryimage"},"image":{"@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg","datePublished":"2024-04-16T13:00:00+00:00","author":{"@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/#primaryimage","url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg","contentUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg","width":562,"height":357},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/spanish\/problemas-de-la-vida\/dios-termina-ganando\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/spanish\/"},{"@type":"ListItem","position":2,"name":"Dios termina ganando"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/spanish\/#website","url":"https:\/\/lifeword.org\/spanish\/","name":"Lifeword en Espa\u00f1ol","description":"Palabras De Vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18","name":"Fernanda Posadas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","caption":"Fernanda Posadas"},"url":"https:\/\/lifeword.org\/spanish\/author\/fernanda-posadas\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg",562,357,false],"thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1-150x150.jpeg",150,150,true],"medium":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1-300x191.jpeg",300,191,true],"medium_large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg",562,357,false],"large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg",562,357,false],"1536x1536":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg",562,357,false],"2048x2048":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg",562,357,false],"post-thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1-264x168.jpeg",264,168,true],"lifeword-detail-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg",562,357,false],"lifeword-slider-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg",562,357,false],"lifeword-list-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg",562,357,false],"gform-image-choice-sm":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg",300,191,false],"gform-image-choice-md":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg",400,254,false],"gform-image-choice-lg":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/04\/Image-1.jpeg",562,357,false]},"uagb_author_info":{"display_name":"Fernanda Posadas","author_link":"https:\/\/lifeword.org\/spanish\/author\/fernanda-posadas\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00a1Dios ya venci\u00f3! Entr\u00e9gale tus batallas.","_links":{"self":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/comments?post=2089"}],"version-history":[{"count":1,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2089\/revisions"}],"predecessor-version":[{"id":2091,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2089\/revisions\/2091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media\/2090"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media?parent=2089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/categories?post=2089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/tags?post=2089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}