{"id":2040,"date":"2024-02-14T13:30:00","date_gmt":"2024-02-14T18:30:00","guid":{"rendered":"https:\/\/lifeword.org\/spanish\/?p=2040"},"modified":"2024-02-14T14:10:20","modified_gmt":"2024-02-14T19:10:20","slug":"ve-hacia-el","status":"publish","type":"post","link":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/","title":{"rendered":"Ve hacia \u00c9L"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Baj\u00e9 del autob\u00fas, mis pies tocaron la acera, y comenc\u00e9 mi caminata hacia la escuela. Era la misma rutina que hab\u00eda seguido el d\u00eda anterior y los d\u00edas anteriores. Nada fuera de lo com\u00fan. Encontr\u00e9 a mi grupo de amigos en las gradas, sonre\u00ed y les salud\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Silencio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me voltearon los ojos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amigos que me daban la espalda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso a los 40 a\u00f1os, casi puedo sentir esas mismas emociones queriendo surgir. Era una sensaci\u00f3n abrumadora de dolor, soledad y desconcierto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 hab\u00eda hecho yo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comenzaron los susurros. Secretos pasados de uno a otro. Y luego, como si estuvieran sincronizados, todos recogieron sus libros y bolsas y se fueron sin decir una sola palabra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero no empieces a sentir l\u00e1stima por m\u00ed. Lo admitir\u00e9, yo tambi\u00e9n era tan culpable como ellos. Sab\u00eda lo que estaba pasando. Hab\u00eda sido parte de ese mismo juego hace una semana cuando decidimos ignorar a otra persona del grupo. Fue horrible, rid\u00edculo y vergonzoso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero ese d\u00eda, supe el verdadero significado de la traici\u00f3n. Sent\u00ed como si todo el mundo estuviera en mi contra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lucas 22:47-48<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>47<\/sup>\u00a0Mientras \u00e9l a\u00fan hablaba, se present\u00f3 una turba; y el que se llamaba Judas, uno de los doce, iba al frente de ellos; y se acerc\u00f3 hasta Jes\u00fas para besarle.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>48<\/sup>\u00a0Entonces Jes\u00fas le dijo: Judas, \u00bfcon un beso entregas al Hijo del Hombre?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una turba. Una multitud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siendo conducida por uno de Sus amigos m\u00e1s cercanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hemos estado hablando del lado humano de Jes\u00fas. \u00bfPuedes imaginar lo que sinti\u00f3 en este momento? Quiero decir, \u00c9l sab\u00eda que se estaba preparando para morir, pero \u00bfhizo eso m\u00e1s f\u00e1cil la traici\u00f3n de Su amigo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puedo sentir la dolorosa desilusi\u00f3n cuando Judas se acerc\u00f3 con un beso, un saludo tradicional entre hombres. Entre amigos. Entre familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La multitud. Guardias romanos, los l\u00edderes religiosos, todos llegando para finalmente deshacerse de Jes\u00fas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, todo estaba de acuerdo con el plan de Dios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mira, el mundo est\u00e1 contra Jes\u00fas. El pr\u00edncipe de este mundo, Satan\u00e1s, gobierna aqu\u00ed. El mundo piensa que el mal es bueno y que el bien es malo, todo por su perversi\u00f3n retorcida y su deseo de ver a las personas destruidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos d\u00edas, puedes sentir que el mundo est\u00e1 en tu contra. Tal vez se presente en forma de un gran error en el trabajo, una situaci\u00f3n en tu familia, o la traici\u00f3n de amigos. Pero d\u00e9jame recordarte esto: no es el fin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dios tiene un prop\u00f3sito y un plan. Usar\u00e1 lo que sea que est\u00e9s pasando para hacerte crecer, ense\u00f1arte, entrenarte y mejorarte. Acude a \u00c9l en tu desesperaci\u00f3n, enojo, dolor y frustraci\u00f3n. Permite que \u00c9l trabaje todas las cosas para tu bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juan 16:33<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup>33<\/sup>\u00a0Estas cosas os he hablado para que en m\u00ed teng\u00e1is paz. En el mundo tendr\u00e9is aflicci\u00f3n; pero confiad, yo he vencido al mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfConf\u00edas en \u00c9l hoy para hacer eso?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Copyright \u00a9 2023 by Yalanda Merrell\u00a0<\/em><\/strong><a href=\"http:\/\/lifeword.org\/\"><strong><em>Lifeword.org<\/em><\/strong><\/a><strong><em>. All rights reserved. No part of this article may be reproduced or reprinted without permission in writing from\u00a0<\/em><\/strong><a href=\"http:\/\/lifeword.org\/\"><strong><em>Lifeword.org<\/em><\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ve hac\u00eda \u00c9l en tu desesperaci\u00f3n, enojo, y dolor. <\/p>\n","protected":false},"author":97,"featured_media":2041,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[1640,1639,1631],"tags":[2884,1579,31,484,2883],"class_list":["post-2040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crecimiento-espiritual","category-problemas-de-la-vida","category-vida-cristiana","tag-confianza-en-dios","tag-el-mundo","tag-jesus","tag-sacrificio","tag-traicion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ve hacia \u00c9L - Lifeword en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ve hacia \u00c9L - Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"Ve hac\u00eda \u00c9l en tu desesperaci\u00f3n, enojo, y dolor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-14T18:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T19:10:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"562\" \/>\n\t<meta property=\"og:image:height\" content=\"357\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernanda Posadas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernanda Posadas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ve-hacia-el\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ve-hacia-el\\\/\"},\"author\":{\"name\":\"Fernanda Posadas\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\"},\"headline\":\"Ve hacia \u00c9L\",\"datePublished\":\"2024-02-14T18:30:00+00:00\",\"dateModified\":\"2024-02-14T19:10:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ve-hacia-el\\\/\"},\"wordCount\":545,\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ve-hacia-el\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/02\\\/Image-1.jpeg\",\"keywords\":[\"confianza en Dios\",\"El Mundo\",\"Jes\u00fas\",\"sacrificio\",\"traici\u00f3n\"],\"articleSection\":[\"Crecimiento Espiritual\",\"Problemas De La Vida\",\"Vida Cristiana\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ve-hacia-el\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ve-hacia-el\\\/\",\"name\":\"Ve hacia \u00c9L - Lifeword en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ve-hacia-el\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ve-hacia-el\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/02\\\/Image-1.jpeg\",\"datePublished\":\"2024-02-14T18:30:00+00:00\",\"dateModified\":\"2024-02-14T19:10:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ve-hacia-el\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ve-hacia-el\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ve-hacia-el\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/02\\\/Image-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/02\\\/Image-1.jpeg\",\"width\":562,\"height\":357},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/ve-hacia-el\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ve hacia \u00c9L\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\",\"name\":\"Lifeword en Espa\u00f1ol\",\"description\":\"Palabras De Vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/bb6a6df7165299ffd2e56671c2c5ae18\",\"name\":\"Fernanda Posadas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g\",\"caption\":\"Fernanda Posadas\"},\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/author\\\/fernanda-posadas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ve hacia \u00c9L - Lifeword en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/","og_locale":"es_ES","og_type":"article","og_title":"Ve hacia \u00c9L - Lifeword en Espa\u00f1ol","og_description":"Ve hac\u00eda \u00c9l en tu desesperaci\u00f3n, enojo, y dolor.","og_url":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/","og_site_name":"Lifeword en Espa\u00f1ol","article_published_time":"2024-02-14T18:30:00+00:00","article_modified_time":"2024-02-14T19:10:20+00:00","og_image":[{"width":562,"height":357,"url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg","type":"image\/jpeg"}],"author":"Fernanda Posadas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fernanda Posadas","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/#article","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/"},"author":{"name":"Fernanda Posadas","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18"},"headline":"Ve hacia \u00c9L","datePublished":"2024-02-14T18:30:00+00:00","dateModified":"2024-02-14T19:10:20+00:00","mainEntityOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/"},"wordCount":545,"image":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg","keywords":["confianza en Dios","El Mundo","Jes\u00fas","sacrificio","traici\u00f3n"],"articleSection":["Crecimiento Espiritual","Problemas De La Vida","Vida Cristiana"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/","url":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/","name":"Ve hacia \u00c9L - Lifeword en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/#primaryimage"},"image":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg","datePublished":"2024-02-14T18:30:00+00:00","dateModified":"2024-02-14T19:10:20+00:00","author":{"@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/#primaryimage","url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg","contentUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg","width":562,"height":357},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/ve-hacia-el\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/spanish\/"},{"@type":"ListItem","position":2,"name":"Ve hacia \u00c9L"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/spanish\/#website","url":"https:\/\/lifeword.org\/spanish\/","name":"Lifeword en Espa\u00f1ol","description":"Palabras De Vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/bb6a6df7165299ffd2e56671c2c5ae18","name":"Fernanda Posadas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e2c30179e76143fdf3a9dab8ded821cf5a681affb1eeba23f9c638fbb12237f?s=96&d=mm&r=g","caption":"Fernanda Posadas"},"url":"https:\/\/lifeword.org\/spanish\/author\/fernanda-posadas\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg",562,357,false],"thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1-150x150.jpeg",150,150,true],"medium":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1-300x191.jpeg",300,191,true],"medium_large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg",562,357,false],"large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg",562,357,false],"1536x1536":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg",562,357,false],"2048x2048":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg",562,357,false],"post-thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1-264x168.jpeg",264,168,true],"lifeword-detail-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg",562,357,false],"lifeword-slider-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg",562,357,false],"lifeword-list-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg",562,357,false],"gform-image-choice-sm":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg",300,191,false],"gform-image-choice-md":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg",400,254,false],"gform-image-choice-lg":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2024\/02\/Image-1.jpeg",562,357,false]},"uagb_author_info":{"display_name":"Fernanda Posadas","author_link":"https:\/\/lifeword.org\/spanish\/author\/fernanda-posadas\/"},"uagb_comment_info":0,"uagb_excerpt":"Ve hac\u00eda \u00c9l en tu desesperaci\u00f3n, enojo, y dolor.","_links":{"self":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/comments?post=2040"}],"version-history":[{"count":1,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2040\/revisions"}],"predecessor-version":[{"id":2042,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/2040\/revisions\/2042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media\/2041"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media?parent=2040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/categories?post=2040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/tags?post=2040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}