{"id":1655,"date":"2022-07-22T11:11:13","date_gmt":"2022-07-22T16:11:13","guid":{"rendered":"https:\/\/lifeword.org\/spanish\/?p=1655"},"modified":"2022-07-22T11:11:16","modified_gmt":"2022-07-22T16:11:16","slug":"guiame-senor","status":"publish","type":"post","link":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/","title":{"rendered":"Gu\u00edame Se\u00f1or"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Lo escucho todo el tiempo\u2026 Si quieres buenos trabajadores, tienes que tener un gran liderazgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces, \u00bfqu\u00e9 hace a un gran l\u00edder? Para m\u00ed, es alguien que est\u00e1 en las trincheras de la batalla. No est\u00e1 en la parte de atr\u00e1s ordenando que marchemos hacia adelante, sino que lideran la carga. Un l\u00edder es alguien que inspira y fomenta la unidad. Reconocen a los trabajadores por sus logros y utilizan sus fortalezas. Un l\u00edder toma decisiones dif\u00edciles que se alinean con la misi\u00f3n, no siempre lo que es popular entre la gente. Escuchan y hacen cambios en consecuencia, seg\u00fan sea necesario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPero qui\u00e9n los lidera? Todo gran l\u00edder tiene un mentor, un h\u00e9roe, alguien que los gu\u00eda para elegir la integridad sobre la ganancia, la compasi\u00f3n sobre la indiferencia y un coraz\u00f3n de siervo sobre el orgullo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un art\u00edculo de la revista Forbes, Carol Sankar hizo una pregunta a las 21 mujeres m\u00e1s exitosas en los negocios: \u00ab\u00bfQu\u00e9 creen que contribuy\u00f3 a su \u00e9xito?\u00bb Sin vacilaci\u00f3n ni inferencia, todas las encuestadas dijeron que fue la inversi\u00f3n de su tiempo con grandes mentores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tengo mentores en mi vida laboral y en mi personal. Y cada una de ellas tiene a alguien a quien tambi\u00e9n miran. Ellos tambi\u00e9n tienen a alguien que los gu\u00eda y los alienta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEntonces respondi\u00f3 Mois\u00e9s a Jehov\u00e1, diciendo, ponga Jehov\u00e1, Dios de los esp\u00edritus de toda carne, un var\u00f3n sobre la congregaci\u00f3n, que salga delante de ellos y que entre delante de ellos, que los saque y los introduzca, para que la congregaci\u00f3n de Jehov\u00e1 no sea como ovejas sin pastor. Y Jehov\u00e1 dijo a Mois\u00e9s: Toma a Josu\u00e9&nbsp;hijo de Nun, var\u00f3n en el cual hay esp\u00edritu, y pondr\u00e1s tu mano sobre \u00e9l; y lo pondr\u00e1s delante del sacerdote Eleazar, y delante de toda la congregaci\u00f3n; y le dar\u00e1s el cargo en presencia de ellos.\u00bb (N\u00fameros 27:15-19)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A medida que se acerca el momento de que los hijos conquisten la tierra prometida, Dios le recuerda a Mois\u00e9s que no le permitir\u00e1 entrar por su desobediencia. Mois\u00e9s entiende que le queda poco tiempo y desea nombrar un nuevo l\u00edder sobre el pueblo de Israel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Josu\u00e9, un l\u00edder probado ya, es seleccionado por Dios mismo para guiar a su pueblo. Entonces, \u00bfc\u00f3mo se convierte Josu\u00e9 en un gran l\u00edder? Sus mentores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mois\u00e9s y Aar\u00f3n iban delante de \u00e9l. Los mir\u00f3 cuidadosamente, observ\u00f3 buenas y las malas decisiones. Aprendi\u00f3 de ellos. Su buen amigo, Caleb, tambi\u00e9n fue una voz de raz\u00f3n y aliento. Juntos, estos dos hombres obedecieron a Dios cuando la multitud no lo hizo. Y finalmente, como veremos en el libro de Josu\u00e9, Dios es su l\u00edder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNadie te podr\u00e1 hacer frente&nbsp;en todos los d\u00edas de tu vida; como estuve con Mois\u00e9s, estar\u00e9 contigo; no te dejar\u00e9, ni te desamparar\u00e9. Esfu\u00e9rzate y s\u00e9 valiente;&nbsp;porque t\u00fa repartir\u00e1s a este pueblo por heredad la tierra de la cual jur\u00e9 a sus padres que la dar\u00eda a ellos. Solamente esfu\u00e9rzate y s\u00e9 muy valiente, para cuidar de hacer conforme a toda la ley que mi siervo Mois\u00e9s te mand\u00f3; no te apartes de ella ni a diestra ni a siniestra, para que seas prosperado en todas las cosas que emprendas. Nunca se apartar\u00e1 de tu boca este libro de la ley, sino que de d\u00eda y de noche meditar\u00e1s en \u00e9l, para que guardes y hagas conforme a todo lo que en \u00e9l est\u00e1 escrito; porque entonces har\u00e1s prosperar tu camino, y todo te saldr\u00e1 bien.\u00bb (Josu\u00e9 1:5-8)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 de usted? \u00bfQui\u00e9n est\u00e1 liderando sus decisiones?&nbsp; \u00bfA qui\u00e9n recurre cuando necesita consejo y ayuda? \u00bfQui\u00e9n es su mentor?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abMas yo por la abundancia de tu misericordia entrar\u00e9 en tu casa; adorar\u00e9 hacia tu santo templo en tu temor. Gu\u00edame, Jehov\u00e1, en tu justicia, a causa de mis enemigos; endereza delante de m\u00ed tu camino.\u00bb (Salmos 5:7-8)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gu\u00edanos Se\u00f1or, por el camino de la justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Copyright \u00a9 2021&nbsp;<\/strong><\/em><a href=\"http:\/\/lifeword.org\/\"><em><strong>Lifeword.org<\/strong><\/em><\/a><em><strong>. Todos los derechos reservados. Ninguna parte de este art\u00edculo puede ser reproducida o reimpresa sin el permiso por escrito de <\/strong><\/em><a href=\"http:\/\/lifeword.org\/\"><em><strong>Lifeword.org<\/strong><\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo escucho todo el tiempo\u2026 Si quieres buenos trabajadores, tienes que tener un gran liderazgo. Entonces, \u00bfqu\u00e9 hace a un [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":1656,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[2359,1640,1630,1634,1638,1639,1631],"tags":[],"class_list":["post-1655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-crecimiento-espiritual","category-devocionales","category-discipulado","category-ministerio","category-problemas-de-la-vida","category-vida-cristiana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gu\u00edame Se\u00f1or - Lifeword en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gu\u00edame Se\u00f1or - Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"Lo escucho todo el tiempo\u2026 Si quieres buenos trabajadores, tienes que tener un gran liderazgo. Entonces, \u00bfqu\u00e9 hace a un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-22T16:11:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-22T16:11:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lifeword.org\/spanish\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"562\" \/>\n\t<meta property=\"og:image:height\" content=\"357\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valmori Zelaya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valmori Zelaya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/guiame-senor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/guiame-senor\\\/\"},\"author\":{\"name\":\"Valmori Zelaya\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/2ec627fcc3e9282f48263d34c993681d\"},\"headline\":\"Gu\u00edame Se\u00f1or\",\"datePublished\":\"2022-07-22T16:11:13+00:00\",\"dateModified\":\"2022-07-22T16:11:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/guiame-senor\\\/\"},\"wordCount\":741,\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/guiame-senor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/07\\\/Lead-Me-Lord.jpg\",\"articleSection\":[\"Blog\",\"Crecimiento Espiritual\",\"Devocionales\",\"Discipulado\",\"Ministerio\",\"Problemas De La Vida\",\"Vida Cristiana\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/guiame-senor\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/guiame-senor\\\/\",\"name\":\"Gu\u00edame Se\u00f1or - Lifeword en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/guiame-senor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/guiame-senor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/07\\\/Lead-Me-Lord.jpg\",\"datePublished\":\"2022-07-22T16:11:13+00:00\",\"dateModified\":\"2022-07-22T16:11:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/2ec627fcc3e9282f48263d34c993681d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/guiame-senor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/guiame-senor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/guiame-senor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/07\\\/Lead-Me-Lord.jpg\",\"contentUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/07\\\/Lead-Me-Lord.jpg\",\"width\":562,\"height\":357},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/guiame-senor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gu\u00edame Se\u00f1or\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\",\"name\":\"Lifeword en Espa\u00f1ol\",\"description\":\"Palabras De Vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/2ec627fcc3e9282f48263d34c993681d\",\"name\":\"Valmori Zelaya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g\",\"caption\":\"Valmori Zelaya\"},\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/author\\\/valmori-zelaya\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gu\u00edame Se\u00f1or - Lifeword en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/","og_locale":"es_ES","og_type":"article","og_title":"Gu\u00edame Se\u00f1or - Lifeword en Espa\u00f1ol","og_description":"Lo escucho todo el tiempo\u2026 Si quieres buenos trabajadores, tienes que tener un gran liderazgo. Entonces, \u00bfqu\u00e9 hace a un [&hellip;]","og_url":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/","og_site_name":"Lifeword en Espa\u00f1ol","article_published_time":"2022-07-22T16:11:13+00:00","article_modified_time":"2022-07-22T16:11:16+00:00","og_image":[{"width":562,"height":357,"url":"https:\/\/lifeword.org\/spanish\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg","type":"image\/jpeg"}],"author":"Valmori Zelaya","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Valmori Zelaya","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/#article","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/"},"author":{"name":"Valmori Zelaya","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/2ec627fcc3e9282f48263d34c993681d"},"headline":"Gu\u00edame Se\u00f1or","datePublished":"2022-07-22T16:11:13+00:00","dateModified":"2022-07-22T16:11:16+00:00","mainEntityOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/"},"wordCount":741,"image":{"@id":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg","articleSection":["Blog","Crecimiento Espiritual","Devocionales","Discipulado","Ministerio","Problemas De La Vida","Vida Cristiana"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/","url":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/","name":"Gu\u00edame Se\u00f1or - Lifeword en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/#primaryimage"},"image":{"@id":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg","datePublished":"2022-07-22T16:11:13+00:00","dateModified":"2022-07-22T16:11:16+00:00","author":{"@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/2ec627fcc3e9282f48263d34c993681d"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/#primaryimage","url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg","contentUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg","width":562,"height":357},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/spanish\/blog\/guiame-senor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/spanish\/"},{"@type":"ListItem","position":2,"name":"Gu\u00edame Se\u00f1or"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/spanish\/#website","url":"https:\/\/lifeword.org\/spanish\/","name":"Lifeword en Espa\u00f1ol","description":"Palabras De Vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/2ec627fcc3e9282f48263d34c993681d","name":"Valmori Zelaya","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g","caption":"Valmori Zelaya"},"url":"https:\/\/lifeword.org\/spanish\/author\/valmori-zelaya\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg",562,357,false],"thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord-150x150.jpg",150,150,true],"medium":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord-300x191.jpg",300,191,true],"medium_large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg",562,357,false],"large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg",562,357,false],"1536x1536":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg",562,357,false],"2048x2048":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg",562,357,false],"post-thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord-264x168.jpg",264,168,true],"lifeword-detail-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg",562,357,false],"lifeword-slider-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg",562,357,false],"lifeword-list-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg",562,357,false],"gform-image-choice-sm":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg",300,191,false],"gform-image-choice-md":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg",400,254,false],"gform-image-choice-lg":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/07\/Lead-Me-Lord.jpg",562,357,false]},"uagb_author_info":{"display_name":"Valmori Zelaya","author_link":"https:\/\/lifeword.org\/spanish\/author\/valmori-zelaya\/"},"uagb_comment_info":0,"uagb_excerpt":"Lo escucho todo el tiempo\u2026 Si quieres buenos trabajadores, tienes que tener un gran liderazgo. Entonces, \u00bfqu\u00e9 hace a un [&hellip;]","_links":{"self":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/1655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/comments?post=1655"}],"version-history":[{"count":1,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/1655\/revisions"}],"predecessor-version":[{"id":1657,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/1655\/revisions\/1657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media\/1656"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media?parent=1655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/categories?post=1655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/tags?post=1655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}