{"id":1527,"date":"2022-03-28T08:47:39","date_gmt":"2022-03-28T13:47:39","guid":{"rendered":"https:\/\/lifeword.org\/spanish\/?p=1527"},"modified":"2022-03-28T08:47:41","modified_gmt":"2022-03-28T13:47:41","slug":"todas-las-naciones","status":"publish","type":"post","link":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/","title":{"rendered":"Todas las Naciones"},"content":{"rendered":"\n<p>Reservamos un viaje en taxi a Hopkins desde nuestro hotel en Belice. Era la ciudad m\u00e1s cercana, as\u00ed que pensamos que podr\u00edamos disfrutar de algunas compras y caminar para ver qu\u00e9 sitios estaban disponibles.<\/p>\n\n\n\n<p>\u00ab\u00bfCu\u00e1nto tiempo le gustar\u00eda quedarse?\u00bb<\/p>\n\n\n\n<p>Pensamos que unas 2-3 horas estar\u00edan bien y ella dijo que lo agendar\u00eda para que el auto regresara por nosotros a esa hora. Cargamos todas nuestras cosas en una furgoneta peque\u00f1a y nos dirigimos a la ciudad. Pero a medida que nos acerc\u00e1bamos, nos dimos cuenta de que no se parec\u00eda en nada a la playa en la que est\u00e1bamos. Casas improvisadas hechas de hojalata, madera contrachapada vieja y lonas se alineaban en la calle, edificios deteriorados que no hab\u00edan sido tocados en a\u00f1os y sin un alma a la vista. Hasta que entramos en el pueblo. Afuera, al costado del camino, hab\u00eda una lona sostenida por dos palos. Cubr\u00eda una mesa con unos cuencos de madera a la vista. Hab\u00eda dos o tres puestos similares m\u00e1s a lo largo del camino y el hombre se detuvo lentamente frente a un banco. Hablaba poco ingl\u00e9s y pregunt\u00f3 a que hora quer\u00edamos que volviera. Todos nos miramos y dijimos al un\u00edsono, tal vez 20 minutos.<\/p>\n\n\n\n<p>Esas 2-3 horas se volvieron muy cortas, muy r\u00e1pidas.<\/p>\n\n\n\n<p>No ten\u00edamos idea de c\u00f3mo era la ciudad. \u00a1Ni siquiera era un pueblo! Hab\u00eda una peque\u00f1a tienda de comestibles, una banca junto a una \u00abcomisar\u00eda\u00bb que ten\u00eda una bicicleta encadenada afuera (no estoy seguro de c\u00f3mo manejaban las persecuciones a alta velocidad) y un peque\u00f1o bar con un \u00e1rea al aire libre para comer y beber. Hab\u00eda una peque\u00f1a tienda y, por supuesto, la playa.&nbsp; Pero la playa estaba muy sucia. La basura cubr\u00eda la arena y el agua.<br>Y nadie hablaba bien ingl\u00e9s. Solo nos miraron.<\/p>\n\n\n\n<p>Estaba enfermo del estomago. En qu\u00e9 nos hab\u00edamos metido. El miedo se apoder\u00f3 de m\u00ed. Esto no es lo que pens\u00e1bamos que ser\u00eda. Nadie parec\u00eda amigable o servicial. Y yo estaba listo para volver al hotel inmediatamente.<\/p>\n\n\n\n<p>Durante a\u00f1os, he escuchado a la gente decirle a los extranjeros: \u201c\u00a1Regresa a tu propio pa\u00eds! \u00a1Aprende a hablar ingl\u00e9s!\u201d<\/p>\n\n\n\n<p>Pero en ese momento, me di cuenta de c\u00f3mo se deben sentir. Estar en una tierra extra\u00f1a que pensaste que ser\u00eda maravillosa, solo para que la gente te trate horriblemente porque no puedes hablar su idioma. Las miradas. El miedo. El deseo de estar en cualquier lugar menos all\u00ed.<\/p>\n\n\n\n<p>En \u00c9xodo 22:21 Dios dice: \u00abY al extranjero no enga\u00f1ar\u00e1s ni angustiar\u00e1s, porque extranjeros fuisteis vosotros en la tierra de Egipto.\u00bb<\/p>\n\n\n\n<p>Lev\u00edticos 19:33-34 dice, \u00abCuando el extranjero morare con vosotros en vuestra tierra, no le oprimir\u00e9is. Como a un natural de vosotros tendr\u00e9is al extranjero que more entre vosotros, y lo amar\u00e1s como a ti mismo; porque extranjeros fuisteis en la tierra de Egipto.&nbsp;Yo Jehov\u00e1 vuestro Dios.\u00bb<\/p>\n\n\n\n<p>\u00c1malos como a ti mismo.<\/p>\n\n\n\n<p>Culpable.<\/p>\n\n\n\n<p>\u00bfPor qu\u00e9 tratamos a las personas de esta manera? Especialmente como cristianos. Cristo nos llama a amar a nuestro pr\u00f3jimo.<\/p>\n\n\n\n<p>\u00abY he aqu\u00ed un int\u00e9rprete de la ley se levant\u00f3 y dijo, para probarle:&nbsp;Maestro, \u00bfhaciendo qu\u00e9 cosa heredar\u00e9 la vida eterna? \u00c9l le dijo: \u00bfQu\u00e9 est\u00e1 escrito en la ley? \u00bfC\u00f3mo lees? Aquel, respondiendo, dijo: Amar\u00e1s al Se\u00f1or tu Dios con todo tu coraz\u00f3n, y con toda tu alma, y con todas tus fuerzas, y con toda tu mente;&nbsp;y a tu pr\u00f3jimo como a ti mismo. Y le dijo: Bien has respondido; haz esto, y vivir\u00e1s. Pero \u00e9l, queriendo justificarse a s\u00ed mismo, dijo a Jes\u00fas: \u00bfY qui\u00e9n es mi pr\u00f3jimo? (Lucas 10:25-29)<\/p>\n\n\n\n<p>Jes\u00fas respondi\u00f3 con una par\u00e1bola sobre un hombre que fue atacado por ladrones y dado por muerto. Un sacerdote pas\u00f3 y no hizo nada. Pas\u00f3 un levita y \u00e9l tambi\u00e9n pas\u00f3 de largo. Pero un samaritano, considerado menos por la sociedad, se detuvo a ayudar. Hizo todo lo posible para curar las heridas del hombre, conseguirle un lugar donde quedarse y pagar todo lo que el hombre necesitaba.<\/p>\n\n\n\n<p>Entonces Jes\u00fas le pregunt\u00f3 al int\u00e9rprete de la ley: \u00bfQui\u00e9n, pues, de estos tres te parece que fue el pr\u00f3jimo del que cay\u00f3 en manos de los ladrones? \u00c9l dijo: El que us\u00f3 de misericordia con \u00e9l.&nbsp; Entonces Jes\u00fas le dijo: Ve, y haz t\u00fa lo mismo.\u00bb Lucas 10:36-37)<\/p>\n\n\n\n<p>Amigos que estamos haciendo \u00bfCu\u00e1l es nuestra misi\u00f3n en esta tierra? \u00a1Dios nos llam\u00f3 a ir y compartir el evangelio! Pero, \u00bfc\u00f3mo podemos hacer eso de una manera excelente si ni siquiera podemos hacerlo de una manera peque\u00f1a? \u00bfPor qu\u00e9 debemos esperar que alguien escuche nuestro mensaje cuando hablamos con una lengua llena de ira, odio y repugnancia? \u00bfPor qu\u00e9 querr\u00edan convertirse en cristianos cuando actuamos de manera ego\u00edsta, con odio y no seguimos lo que dice nuestro Dios?<\/p>\n\n\n\n<p>Ni siquiera entendemos lo que tenemos. Nosotros tenemos el evangelio! \u00a1Este es el poder de Dios que da vida, salva almas, asegura la eternidad! \u00a1Tenemos el poder de salvar! \u00a1\u00c9l nos SALV\u00d3! \u00bfQui\u00e9nes somos nosotros para elegir qui\u00e9n recibe este mensaje? \u00bfEstamos de acuerdo con enviar misioneros a predicar el evangelio a otros pa\u00edses mientras los extranjeros se queden all\u00ed?<\/p>\n\n\n\n<p>&nbsp;\u00abPor tanto, id, y haced disc\u00edpulos a todas las naciones,&nbsp;bautiz\u00e1ndolos en el nombre del Padre, y del Hijo, y del Esp\u00edritu Santo: Ense\u00f1\u00e1ndoles que guarden todas las cosas que os he mandado; y he aqu\u00ed yo estoy con vosotros todos los d\u00edas, hasta el fin del mundo.&nbsp; Am\u00e9n.\u00bb (Mateo 28:19-20)<\/p>\n\n\n\n<p>TODAS LAS NACIONES. Ya sea que vayamos a ellos o que Dios nos los traiga, debemos amarlos como a nosotros mismos.<\/p>\n\n\n\n<p>\u00abExam\u00edname, oh Dios, y conoce mi coraz\u00f3n; pru\u00e9bame y conoce mis pensamientos: Y ve si hay en m\u00ed camino de perversidad,Y gu\u00edame en el camino eterno.\u00bb (Salmos 139:23-24)<\/p>\n\n\n\n<p>Hoy, encontr\u00e9monos ocupados en los asuntos de nuestro Padre. Comparte el evangelio mostrando Su amor y misericordia a todos. Se\u00f1or, perd\u00f3nanos. Los amas tal como me amabas. Estaba miserable y perdido y a\u00fan elegiste salvarme. No soy mejor que cualquier otro hombre. No merec\u00eda tu misericordia, pero me la diste de todos modos. Ay\u00fadame a hacer lo mismo.<\/p>\n\n\n\n<p><em><strong>Copyright \u00a9 2021&nbsp;<\/strong><\/em><a href=\"http:\/\/lifeword.org\/\"><em><strong>Lifeword.org<\/strong><\/em><\/a><em><strong>. Todos los derechos reservados. Ninguna parte de este art\u00edculo puede ser reproducida o reimpresa sin el permiso por escrito de <\/strong><\/em><a href=\"http:\/\/lifeword.org\/\"><em><strong>Lifeword.org<\/strong><\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reservamos un viaje en taxi a Hopkins desde nuestro hotel en Belice. Era la ciudad m\u00e1s cercana, as\u00ed que pensamos [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":1528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[2359,1640,1630,1638,1639,1631],"tags":[],"class_list":["post-1527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-crecimiento-espiritual","category-devocionales","category-ministerio","category-problemas-de-la-vida","category-vida-cristiana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Todas las Naciones - Lifeword en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todas las Naciones - Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"Reservamos un viaje en taxi a Hopkins desde nuestro hotel en Belice. Era la ciudad m\u00e1s cercana, as\u00ed que pensamos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-28T13:47:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-28T13:47:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"562\" \/>\n\t<meta property=\"og:image:height\" content=\"357\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valmori Zelaya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valmori Zelaya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/todas-las-naciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/todas-las-naciones\\\/\"},\"author\":{\"name\":\"Valmori Zelaya\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/2ec627fcc3e9282f48263d34c993681d\"},\"headline\":\"Todas las Naciones\",\"datePublished\":\"2022-03-28T13:47:39+00:00\",\"dateModified\":\"2022-03-28T13:47:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/todas-las-naciones\\\/\"},\"wordCount\":1138,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/todas-las-naciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/03\\\/All-Nations.jpg\",\"articleSection\":[\"Blog\",\"Crecimiento Espiritual\",\"Devocionales\",\"Ministerio\",\"Problemas De La Vida\",\"Vida Cristiana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/todas-las-naciones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/todas-las-naciones\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/todas-las-naciones\\\/\",\"name\":\"Todas las Naciones - Lifeword en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/todas-las-naciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/todas-las-naciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/03\\\/All-Nations.jpg\",\"datePublished\":\"2022-03-28T13:47:39+00:00\",\"dateModified\":\"2022-03-28T13:47:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/2ec627fcc3e9282f48263d34c993681d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/todas-las-naciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/todas-las-naciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/todas-las-naciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/03\\\/All-Nations.jpg\",\"contentUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/03\\\/All-Nations.jpg\",\"width\":562,\"height\":357},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/blog\\\/todas-las-naciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todas las Naciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\",\"name\":\"Lifeword en Espa\u00f1ol\",\"description\":\"Palabras De Vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/2ec627fcc3e9282f48263d34c993681d\",\"name\":\"Valmori Zelaya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g\",\"caption\":\"Valmori Zelaya\"},\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/author\\\/valmori-zelaya\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todas las Naciones - Lifeword en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/","og_locale":"es_ES","og_type":"article","og_title":"Todas las Naciones - Lifeword en Espa\u00f1ol","og_description":"Reservamos un viaje en taxi a Hopkins desde nuestro hotel en Belice. Era la ciudad m\u00e1s cercana, as\u00ed que pensamos [&hellip;]","og_url":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/","og_site_name":"Lifeword en Espa\u00f1ol","article_published_time":"2022-03-28T13:47:39+00:00","article_modified_time":"2022-03-28T13:47:41+00:00","og_image":[{"width":562,"height":357,"url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg","type":"image\/jpeg"}],"author":"Valmori Zelaya","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Valmori Zelaya","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/#article","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/"},"author":{"name":"Valmori Zelaya","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/2ec627fcc3e9282f48263d34c993681d"},"headline":"Todas las Naciones","datePublished":"2022-03-28T13:47:39+00:00","dateModified":"2022-03-28T13:47:41+00:00","mainEntityOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/"},"wordCount":1138,"commentCount":0,"image":{"@id":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg","articleSection":["Blog","Crecimiento Espiritual","Devocionales","Ministerio","Problemas De La Vida","Vida Cristiana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/","url":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/","name":"Todas las Naciones - Lifeword en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/#primaryimage"},"image":{"@id":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg","datePublished":"2022-03-28T13:47:39+00:00","dateModified":"2022-03-28T13:47:41+00:00","author":{"@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/2ec627fcc3e9282f48263d34c993681d"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/#primaryimage","url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg","contentUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg","width":562,"height":357},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/spanish\/blog\/todas-las-naciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/spanish\/"},{"@type":"ListItem","position":2,"name":"Todas las Naciones"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/spanish\/#website","url":"https:\/\/lifeword.org\/spanish\/","name":"Lifeword en Espa\u00f1ol","description":"Palabras De Vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/2ec627fcc3e9282f48263d34c993681d","name":"Valmori Zelaya","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g","caption":"Valmori Zelaya"},"url":"https:\/\/lifeword.org\/spanish\/author\/valmori-zelaya\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg",562,357,false],"thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations-150x150.jpg",150,150,true],"medium":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations-300x191.jpg",300,191,true],"medium_large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg",562,357,false],"large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg",562,357,false],"1536x1536":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg",562,357,false],"2048x2048":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg",562,357,false],"post-thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations-264x168.jpg",264,168,true],"lifeword-detail-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg",562,357,false],"lifeword-slider-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg",562,357,false],"lifeword-list-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg",562,357,false],"gform-image-choice-sm":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg",300,191,false],"gform-image-choice-md":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg",400,254,false],"gform-image-choice-lg":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-Nations.jpg",562,357,false]},"uagb_author_info":{"display_name":"Valmori Zelaya","author_link":"https:\/\/lifeword.org\/spanish\/author\/valmori-zelaya\/"},"uagb_comment_info":0,"uagb_excerpt":"Reservamos un viaje en taxi a Hopkins desde nuestro hotel en Belice. Era la ciudad m\u00e1s cercana, as\u00ed que pensamos [&hellip;]","_links":{"self":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/1527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/comments?post=1527"}],"version-history":[{"count":1,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/1527\/revisions"}],"predecessor-version":[{"id":1529,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/1527\/revisions\/1529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media\/1528"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media?parent=1527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/categories?post=1527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/tags?post=1527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}