{"id":1499,"date":"2022-03-01T09:59:02","date_gmt":"2022-03-01T14:59:02","guid":{"rendered":"https:\/\/lifeword.org\/spanish\/?p=1499"},"modified":"2022-03-01T09:59:44","modified_gmt":"2022-03-01T14:59:44","slug":"todo-o-nada%ef%bf%bc","status":"publish","type":"post","link":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/","title":{"rendered":"Todo o Nada"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Una dulce familia recibi\u00f3 recientemente un cachorro de parte nuestra. Estaban muy emocionados, pero cuando lleg\u00f3 el momento de llevarlo a casa, llamaron de inmediato con preocupaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de tenerlo en casa por solo una hora m\u00e1s o menos, son\u00f3 el tel\u00e9fono y empezaron a llegar las preguntas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El muerde. \u00bfSiempre morder\u00e1?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 hacemos con sus mordeduras?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muerde su cama para perros y trata de romperla. \u00bfQu\u00e9 hacemos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1nta comida le damos de comer?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 tan a menudo va al ba\u00f1o? \u00bfCu\u00e1l es su horario?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1nta agua bebe? \u00bfDebe beber cada 2 horas?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tiene mucha energ\u00eda. \u00bfSer\u00e1 as\u00ed todo el tiempo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando vieron las fotos por primera vez, \u00e9l era adorable para ellos. Un cachorro dulce e inocente. So\u00f1aban con los mimos, el pelaje suave, el aliento de cachorro y los lametones en la cara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">So\u00f1aban con dar largos y agradables paseos con \u00e9l en un d\u00eda soleado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pensaban en d\u00edas jugando en la casa con un dulce cachorro en su regazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto fue lo que llamo su atenci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claro, \u00e9l es todas esas cosas, pero es un cachorro, as\u00ed que es m\u00e1s. No podemos elegir lo que queremos de un cachorro: es todo o nada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fueron honestos y dijeron que nunca antes hab\u00edan tenido uno. Su hijo estaba all\u00ed para ayudar a la madre y a su esposo, pero ella ten\u00eda muchas preguntas. No pod\u00eda pensar en estas cosas \u00abadicionales\u00bb que no sab\u00eda que ven\u00edan con un cachorro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le expliqu\u00e9 que los cachorros son como beb\u00e9s. Ellos ser\u00e1n en\u00e9rgicos por un rato y luego dormir\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le expliqu\u00e9 que necesita juguetes para morder (es un laboratorio) y necesita que le ense\u00f1en lo que puede y no puede masticar o poner en la boca. Hablamos sobre comida, golosinas, entrenamiento para ir al ba\u00f1o, vacunas y m\u00e1s. Todas estas cosas ya estaban cubiertas en el paquete de informaci\u00f3n, pero nos dimos cuenta de que no todos leen los consejos \u00fatiles ya incluidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente estaba viendo a este cachorro por todo lo que era, un labrador y un cachorro 100%. Por lo tanto, ten\u00eda que calcular el costo y decidir qu\u00e9 hacer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfLo aceptar\u00eda por lo que era o se alejar\u00eda de la verdad que hab\u00eda descubierto?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy en el libro de \u00c9xodo podemos ver que la obediencia a la Palabra de Dios es vital y, con Dios, es todo o nada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cY aconteci\u00f3 en el camino, que en una posada Jehov\u00e1 le sali\u00f3 al encuentro, y quiso matarlo. Entonces S\u00e9fora tom\u00f3 un pedernal afilado y cort\u00f3 el prepucio de su hijo, y lo ech\u00f3 a sus pies, diciendo: A la verdad t\u00fa me eres un esposo de sangre. As\u00ed le dej\u00f3 luego ir. Y ella dijo: (Esposo de sangre, a causa de la circuncisi\u00f3n.)\u00bb (\u00c9xodo 4:26)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mois\u00e9s va camino a Egipto, obedeciendo lo que Dios le dijo que hiciera. Y luego el Se\u00f1or, probablemente con una espada desenvainada, aparece listo para matar a Mois\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Guau! \u00bfQu\u00e9 hizo Mois\u00e9s?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 pecado cometi\u00f3?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPor qu\u00e9 el Se\u00f1or, que estaba hablando con \u00e9l uno a uno antes, ahora quiere matarlo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo primero que vemos aqu\u00ed es que Mois\u00e9s se ha casado fuera de su pueblo, los israelitas. S\u00e9fora era una madianita. Dios sab\u00eda que estos otros grupos de personas adoraban dioses falsos, \u00eddolos, y no ten\u00edan el compromiso con el \u00fanico Dios verdadero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e9fora no sab\u00eda, o si lo sab\u00eda, no le gust\u00f3 el mandato de que todos los israelitas circuncidaran a sus hijos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El segundo pecado que vemos es el pecado de omisi\u00f3n. No fue lo que Mois\u00e9s hizo lo que estuvo mal, fue lo que no hizo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fracas\u00f3 en honrar el pacto entre Dios e Israel al no circuncidar a su hijo. Recuerde que, la circuncisi\u00f3n era la forma en que los israelitas ser\u00edan conocidos como hijos de Dios. Ser\u00edan apartados de todos los dem\u00e1s debido a este procedimiento. S\u00e9fora, enojada, lo hace ella misma y circuncida a su hijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mois\u00e9s se dio cuenta de que no pod\u00eda obedecer a Dios solo en una parte de su vida sino en su totalidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A veces, queremos darle al Se\u00f1or una parte de nosotros, pero no todo. Nuestras actitudes no est\u00e1n alineadas con los mandamientos de Dios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchos dir\u00e1n: \u201cClaro, voy a la iglesia (o asisto en l\u00ednea) el domingo, pero no esta noche. Este d\u00eda es para mi. Gano mi dinero, pagar\u00e9 todo lo que necesito y, aqu\u00ed tienes Se\u00f1or, un billete de $20 porque eso es todo lo que me queda despu\u00e9s de pagar mis facturas y otras cosas. Y, por supuesto, Se\u00f1or, quiero tus bendiciones y respuestas a mis oraciones, incluso servir\u00e9 en tu iglesia si me lo piden, pero esta otra parte de mi vida, eso no es asunto de nadie. Lo que hago en mi tiempo no da\u00f1a a nadie m\u00e1s, as\u00ed que seguir\u00e9 haci\u00e9ndolo.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No podemos darle a Dios solo una parte de nuestra vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9l nos dio todo lo suyo, \u00bfpor qu\u00e9 deber\u00edamos esperar dar menos? Es todo o nada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9l nos ha dado la Palabra escrita para instruirnos y guiarnos. Si no hacemos lo que dice donde \u00c9l ha mandado, somos culpables. Y si hacemos las cosas que dice que no debemos hacer, somos culpables. Nosotros no podemos escoger y elegir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es todo o nada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que la mujer que tuvo que calcular el costo y decidir lo que har\u00eda con su cachorro, \u00bfaceptaremos a Dios por lo que es o nos alejaremos de la verdad que hemos descubierto?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es en serio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Se\u00f1or est\u00e1 ante nosotros con una espada desenvainada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfObedeceremos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Copyright \u00a9 2021&nbsp;<\/strong><\/em><a href=\"http:\/\/lifeword.org\/\"><em><strong>Lifeword.org<\/strong><\/em><\/a><em><strong>. Todos los derechos reservados. Ninguna parte de este art\u00edculo puede ser reproducida o reimpresa sin permiso por escrito de <\/strong><\/em><a href=\"http:\/\/lifeword.org\/\"><em><strong>Lifeword.org<\/strong><\/em><\/a><em><strong>&nbsp;&nbsp;<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una dulce familia recibi\u00f3 recientemente un cachorro de parte nuestra. Estaban muy emocionados, pero cuando lleg\u00f3 el momento de llevarlo [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":1500,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[2359,1640,1630,1639,1631],"tags":[],"class_list":["post-1499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-crecimiento-espiritual","category-devocionales","category-problemas-de-la-vida","category-vida-cristiana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Todo o Nada - Lifeword en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada\ufffc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todo o Nada - Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"Una dulce familia recibi\u00f3 recientemente un cachorro de parte nuestra. Estaban muy emocionados, pero cuando lleg\u00f3 el momento de llevarlo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada\ufffc\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-01T14:59:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-01T14:59:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"562\" \/>\n\t<meta property=\"og:image:height\" content=\"357\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valmori Zelaya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valmori Zelaya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/todo-o-nada%ef%bf%bc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/todo-o-nada%ef%bf%bc\\\/\"},\"author\":{\"name\":\"Valmori Zelaya\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/2ec627fcc3e9282f48263d34c993681d\"},\"headline\":\"Todo o Nada\",\"datePublished\":\"2022-03-01T14:59:02+00:00\",\"dateModified\":\"2022-03-01T14:59:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/todo-o-nada%ef%bf%bc\\\/\"},\"wordCount\":1012,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/todo-o-nada%ef%bf%bc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/03\\\/All-or-Nothing.jpg\",\"articleSection\":[\"Blog\",\"Crecimiento Espiritual\",\"Devocionales\",\"Problemas De La Vida\",\"Vida Cristiana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/todo-o-nada%ef%bf%bc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/todo-o-nada%ef%bf%bc\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/todo-o-nada%ef%bf%bc\\\/\",\"name\":\"Todo o Nada - Lifeword en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/todo-o-nada%ef%bf%bc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/todo-o-nada%ef%bf%bc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/03\\\/All-or-Nothing.jpg\",\"datePublished\":\"2022-03-01T14:59:02+00:00\",\"dateModified\":\"2022-03-01T14:59:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/2ec627fcc3e9282f48263d34c993681d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/todo-o-nada%ef%bf%bc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/todo-o-nada%ef%bf%bc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/todo-o-nada%ef%bf%bc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/03\\\/All-or-Nothing.jpg\",\"contentUrl\":\"https:\\\/\\\/lwlive-wpmedia.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/03\\\/All-or-Nothing.jpg\",\"width\":562,\"height\":357},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/crecimiento-espiritual\\\/todo-o-nada%ef%bf%bc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todo o Nada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/\",\"name\":\"Lifeword en Espa\u00f1ol\",\"description\":\"Palabras De Vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/#\\\/schema\\\/person\\\/2ec627fcc3e9282f48263d34c993681d\",\"name\":\"Valmori Zelaya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g\",\"caption\":\"Valmori Zelaya\"},\"url\":\"https:\\\/\\\/lifeword.org\\\/spanish\\\/author\\\/valmori-zelaya\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todo o Nada - Lifeword en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada\ufffc\/","og_locale":"es_ES","og_type":"article","og_title":"Todo o Nada - Lifeword en Espa\u00f1ol","og_description":"Una dulce familia recibi\u00f3 recientemente un cachorro de parte nuestra. Estaban muy emocionados, pero cuando lleg\u00f3 el momento de llevarlo [&hellip;]","og_url":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada\ufffc\/","og_site_name":"Lifeword en Espa\u00f1ol","article_published_time":"2022-03-01T14:59:02+00:00","article_modified_time":"2022-03-01T14:59:44+00:00","og_image":[{"width":562,"height":357,"url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg","type":"image\/jpeg"}],"author":"Valmori Zelaya","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Valmori Zelaya","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/#article","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/"},"author":{"name":"Valmori Zelaya","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/2ec627fcc3e9282f48263d34c993681d"},"headline":"Todo o Nada","datePublished":"2022-03-01T14:59:02+00:00","dateModified":"2022-03-01T14:59:44+00:00","mainEntityOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/"},"wordCount":1012,"commentCount":0,"image":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg","articleSection":["Blog","Crecimiento Espiritual","Devocionales","Problemas De La Vida","Vida Cristiana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/","url":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/","name":"Todo o Nada - Lifeword en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lifeword.org\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/#primaryimage"},"image":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/#primaryimage"},"thumbnailUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg","datePublished":"2022-03-01T14:59:02+00:00","dateModified":"2022-03-01T14:59:44+00:00","author":{"@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/2ec627fcc3e9282f48263d34c993681d"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/#primaryimage","url":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg","contentUrl":"https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg","width":562,"height":357},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/spanish\/crecimiento-espiritual\/todo-o-nada%ef%bf%bc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/spanish\/"},{"@type":"ListItem","position":2,"name":"Todo o Nada"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/spanish\/#website","url":"https:\/\/lifeword.org\/spanish\/","name":"Lifeword en Espa\u00f1ol","description":"Palabras De Vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lifeword.org\/spanish\/#\/schema\/person\/2ec627fcc3e9282f48263d34c993681d","name":"Valmori Zelaya","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5cfd30b1f770c8299341a50e7ed426dfbb2ef2f4c609c947dd675ddbcfb4e1de?s=96&d=mm&r=g","caption":"Valmori Zelaya"},"url":"https:\/\/lifeword.org\/spanish\/author\/valmori-zelaya\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg",562,357,false],"thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing-150x150.jpg",150,150,true],"medium":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing-300x191.jpg",300,191,true],"medium_large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg",562,357,false],"large":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg",562,357,false],"1536x1536":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg",562,357,false],"2048x2048":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg",562,357,false],"post-thumbnail":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing-264x168.jpg",264,168,true],"lifeword-detail-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg",562,357,false],"lifeword-slider-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg",562,357,false],"lifeword-list-thumb":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg",562,357,false],"gform-image-choice-sm":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg",300,191,false],"gform-image-choice-md":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg",400,254,false],"gform-image-choice-lg":["https:\/\/lwlive-wpmedia.s3.amazonaws.com\/wp-content\/uploads\/sites\/5\/2022\/03\/All-or-Nothing.jpg",562,357,false]},"uagb_author_info":{"display_name":"Valmori Zelaya","author_link":"https:\/\/lifeword.org\/spanish\/author\/valmori-zelaya\/"},"uagb_comment_info":1,"uagb_excerpt":"Una dulce familia recibi\u00f3 recientemente un cachorro de parte nuestra. Estaban muy emocionados, pero cuando lleg\u00f3 el momento de llevarlo [&hellip;]","_links":{"self":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/1499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/comments?post=1499"}],"version-history":[{"count":2,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/1499\/revisions"}],"predecessor-version":[{"id":1502,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/posts\/1499\/revisions\/1502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media\/1500"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/media?parent=1499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/categories?post=1499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeword.org\/spanish\/wp-json\/wp\/v2\/tags?post=1499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}