{"id":9,"date":"2022-12-16T08:37:28","date_gmt":"2022-12-16T08:37:28","guid":{"rendered":"https:\/\/lifeword.org\/mandingo\/mission-vision\/"},"modified":"2022-12-16T10:32:55","modified_gmt":"2022-12-16T10:32:55","slug":"mission-vision","status":"publish","type":"page","link":"https:\/\/lifeword.org\/mandingo\/who-we-are\/mission-vision\/","title":{"rendered":"Mission &#038; Vision"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":5,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mission &amp; Vision - Lifeword - Mandingo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/mandingo\/who-we-are\/mission-vision\/\" \/>\n<meta property=\"og:locale\" content=\"mn_MN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mission &amp; Vision - Lifeword - Mandingo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/mandingo\/who-we-are\/mission-vision\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword - Mandingo\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-16T10:32:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/mandingo\\\/who-we-are\\\/mission-vision\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/mandingo\\\/who-we-are\\\/mission-vision\\\/\",\"name\":\"Mission & Vision - Lifeword - Mandingo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/mandingo\\\/#website\"},\"datePublished\":\"2022-12-16T08:37:28+00:00\",\"dateModified\":\"2022-12-16T10:32:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/mandingo\\\/who-we-are\\\/mission-vision\\\/#breadcrumb\"},\"inLanguage\":\"mnk\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifeword.org\\\/mandingo\\\/who-we-are\\\/mission-vision\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/mandingo\\\/who-we-are\\\/mission-vision\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/mandingo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Who We Are\",\"item\":\"https:\\\/\\\/lifeword.org\\\/mandingo\\\/who-we-are\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mission &#038; Vision\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/mandingo\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/mandingo\\\/\",\"name\":\"Lifeword - Mandingo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/mandingo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"mnk\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mission & Vision - Lifeword - Mandingo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/mandingo\/who-we-are\/mission-vision\/","og_locale":"mn_MN","og_type":"article","og_title":"Mission & Vision - Lifeword - Mandingo","og_url":"https:\/\/lifeword.org\/mandingo\/who-we-are\/mission-vision\/","og_site_name":"Lifeword - Mandingo","article_modified_time":"2022-12-16T10:32:55+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lifeword.org\/mandingo\/who-we-are\/mission-vision\/","url":"https:\/\/lifeword.org\/mandingo\/who-we-are\/mission-vision\/","name":"Mission & Vision - Lifeword - Mandingo","isPartOf":{"@id":"https:\/\/lifeword.org\/mandingo\/#website"},"datePublished":"2022-12-16T08:37:28+00:00","dateModified":"2022-12-16T10:32:55+00:00","breadcrumb":{"@id":"https:\/\/lifeword.org\/mandingo\/who-we-are\/mission-vision\/#breadcrumb"},"inLanguage":"mnk","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifeword.org\/mandingo\/who-we-are\/mission-vision\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/mandingo\/who-we-are\/mission-vision\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/mandingo\/"},{"@type":"ListItem","position":2,"name":"Who We Are","item":"https:\/\/lifeword.org\/mandingo\/who-we-are\/"},{"@type":"ListItem","position":3,"name":"Mission &#038; Vision"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/mandingo\/#website","url":"https:\/\/lifeword.org\/mandingo\/","name":"Lifeword - Mandingo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/mandingo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"mnk"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false,"lifeword-detail-thumb":false,"lifeword-slider-thumb":false,"lifeword-list-thumb":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"lifeword","author_link":"https:\/\/lifeword.org\/mandingo\/author\/lifeword\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/lifeword.org\/mandingo\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/mandingo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lifeword.org\/mandingo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lifeword.org\/mandingo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeword.org\/mandingo\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":1,"href":"https:\/\/lifeword.org\/mandingo\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":10,"href":"https:\/\/lifeword.org\/mandingo\/wp-json\/wp\/v2\/pages\/9\/revisions\/10"}],"up":[{"embeddable":true,"href":"https:\/\/lifeword.org\/mandingo\/wp-json\/wp\/v2\/pages\/5"}],"wp:attachment":[{"href":"https:\/\/lifeword.org\/mandingo\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}