{"id":1,"count":1,"description":"","link":"https:\/\/lifeword.org\/mande\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uncategorized Archives - Lifeword - Mande<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifeword.org\/mande\/category\/uncategorized\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uncategorized Archives - Lifeword - Mande\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifeword.org\/mande\/category\/uncategorized\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeword - Mande\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/mande\\\/category\\\/uncategorized\\\/\",\"url\":\"https:\\\/\\\/lifeword.org\\\/mande\\\/category\\\/uncategorized\\\/\",\"name\":\"Uncategorized Archives - Lifeword - Mande\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/mande\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifeword.org\\\/mande\\\/category\\\/uncategorized\\\/#breadcrumb\"},\"inLanguage\":\"dmn\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/mande\\\/category\\\/uncategorized\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifeword.org\\\/mande\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifeword.org\\\/mande\\\/#website\",\"url\":\"https:\\\/\\\/lifeword.org\\\/mande\\\/\",\"name\":\"Lifeword - Mande\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifeword.org\\\/mande\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"dmn\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uncategorized Archives - Lifeword - Mande","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifeword.org\/mande\/category\/uncategorized\/","og_locale":"en_US","og_type":"article","og_title":"Uncategorized Archives - Lifeword - Mande","og_url":"https:\/\/lifeword.org\/mande\/category\/uncategorized\/","og_site_name":"Lifeword - Mande","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lifeword.org\/mande\/category\/uncategorized\/","url":"https:\/\/lifeword.org\/mande\/category\/uncategorized\/","name":"Uncategorized Archives - Lifeword - Mande","isPartOf":{"@id":"https:\/\/lifeword.org\/mande\/#website"},"breadcrumb":{"@id":"https:\/\/lifeword.org\/mande\/category\/uncategorized\/#breadcrumb"},"inLanguage":"dmn"},{"@type":"BreadcrumbList","@id":"https:\/\/lifeword.org\/mande\/category\/uncategorized\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifeword.org\/mande\/"},{"@type":"ListItem","position":2,"name":"Uncategorized"}]},{"@type":"WebSite","@id":"https:\/\/lifeword.org\/mande\/#website","url":"https:\/\/lifeword.org\/mande\/","name":"Lifeword - Mande","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifeword.org\/mande\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"dmn"}]}},"_links":{"self":[{"href":"https:\/\/lifeword.org\/mande\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeword.org\/mande\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lifeword.org\/mande\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lifeword.org\/mande\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}